{"id":12113,"date":"2021-01-04T18:33:53","date_gmt":"2021-01-04T21:33:53","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=12113"},"modified":"2021-01-04T18:37:21","modified_gmt":"2021-01-04T21:37:21","slug":"governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/","title":{"rendered":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os"},"content":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12087&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12083&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O novo regime ser\u00e1 implantado pelo Conselho Administrativo de Defesa Econ\u00f4mica, quatro minist\u00e9rios, Secret\u00e1ria-Geral da Presid\u00eancia da Rep\u00fablica e sete ag\u00eancias reguladoras.<\/p>\n<p>Segundo informa\u00e7\u00f5es do Minist\u00e9rio da Economia, al\u00e9m da Controladoria-Geral da Uni\u00e3o (CGU), da Advocacia-Geral da Uni\u00e3o (AGU), \u00a0do Banco Central e da Receita Federal, que j\u00e1 mantinham o regime de teletrabalho antes da pandemia, outros 13 \u00f3rg\u00e3os j\u00e1 autorizaram a modalidade em suas unidades.<\/p>\n<p>A Uni\u00e3o pretende manter parte de seus empregados fazendo o expediente de casa, mesmo ap\u00f3s o fim do isolamento social.<\/p>\n<p><strong>Veja lista de \u00f3rg\u00e3os que j\u00e1 autorizaram o teletrabalho permanente at\u00e9 o momento:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ag\u00eancia Nacional das \u00c1guas (ANA)<\/p>\n<p>Ag\u00eancia Nacional de Transportes Terrestres (ANTT)<\/p>\n<p>Minist\u00e9rio da Economia<\/p>\n<p>Minist\u00e9rio da Cidadania<\/p>\n<p>Minist\u00e9rio do Desenvolvimento Regional<\/p>\n<p>Minist\u00e9rio de Minas e Energia<\/p>\n<p>Conselho Administrativo de Defesa Econ\u00f4mica (Cade)<\/p>\n<p>Secretaria-Geral da Presid\u00eancia<\/p>\n<p>Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel)<\/p>\n<p>Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM)<\/p>\n<p>Ag\u00eancia Nacional do Cinema (Ancine)<\/p>\n<p>Ag\u00eancia Nacional de Transportes Aquavi\u00e1rios (Antaq)<\/p>\n<p>Ag\u00eancia Nacional do Petr\u00f3leo (ANP)<\/p>\n<p>&nbsp;<\/p>\n<p>Conforme entendimento do governo federal, o teletrabalho facilita a entrega de resultados e o aumento da efici\u00eancia dos servidores p\u00fablicos.<\/p>\n<p>O servidor que optar pelo modelo \u2013 em regime parcial ou integral \u2013 ter\u00e1 que assinar e cumprir um plano de trabalho definido por cada \u00f3rg\u00e3o considerando suas necessidades e conveni\u00eancia e quais atividades poder\u00e3o ser realizadas a dist\u00e2ncia.<\/p>\n<p>Despesas como energia el\u00e9trica, telefone, internet, entre outras s\u00e3o de responsabilidade do servidor que escolher a modalidade. N\u00e3o haver\u00e1 horas extras ou banco de horas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12090&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseuseguronoclick.com.br%2Fseguros%2Fseguro-auto-novo%2F%3F%26utm_medium%3Dseguros_auto_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_seguro_auto|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12081&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseuseguronoclick.com.br%2Fseguros%2Fseguro-auto-novo%2F%3F%26utm_medium%3Dseguros_auto_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_seguro_auto|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]<strong>Processo<\/strong><\/p>\n<p>As regras est\u00e3o sendo implementadas ao poucos. O Minist\u00e9rio da Economia, por exemplo, disponibilizou o sistema para gest\u00e3o do teletrabalho \u00e0s unidades da pasta. Os gestores optaram pela solu\u00e7\u00e3o desenvolvida pela Superintend\u00eancia de Seguros Privados (Susep).<\/p>\n<p>Al\u00e9m desse sistema, outros \u00f3rg\u00e3os e entidades tamb\u00e9m t\u00eam acesso ao Programa de Gest\u00e3o da Controladoria-Geral da Uni\u00e3o (CGU), com as evolu\u00e7\u00f5es realizadas pelo Minist\u00e9rio do Meio Ambiente (MMA).<\/p>\n<p>\u201cA situa\u00e7\u00e3o de emerg\u00eancia em sa\u00fade p\u00fablica, decretada no in\u00edcio do ano (de 2020) por causa da pandemia, imp\u00f4s o trabalho remoto para muitos brasileiros, tanto na iniciativa privada como no setor p\u00fablico. Entre mar\u00e7o e setembro de 2020, cerca de 50% dos servidores p\u00fablicos federais desempenharam suas atividades a partir de suas casas. Em alguns \u00f3rg\u00e3os, como no Minist\u00e9rio da Educa\u00e7\u00e3o, esse percentual chegou a 98% durante certos per\u00edodos\u201d, explica o Minist\u00e9rio da Economia, em nota.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Repercuss\u00e3o<\/strong><\/p>\n<p>O presidente do F\u00f3rum Nacional das Carreiras T\u00edpicas de Estado (Fonacate), Rudinei Marques, comenta que, antes da pandemia, \u00f3rg\u00e3os do governo federal j\u00e1 haviam adotado o teletrabalho.<\/p>\n<p>\u201cO que houve desde mar\u00e7o, nesses \u00f3rg\u00e3os, foi a amplia\u00e7\u00e3o a todo o quadro funcional, e a ado\u00e7\u00e3o da sistem\u00e1tica pelos \u00f3rg\u00e3os que ainda n\u00e3o a tinham adotado. Como o teletrabalho deu bons resultados, em termos de economia para o Estado e incremento de produtividade, dever\u00e1 ser mantido, ainda que conjugado com atividades presenciais\u201d, explica.<\/p>\n<p>Uma das fortes cr\u00edticas \u00e9 a falta de incentivo para a modalidade de trabalho. \u201cOcorre que parte dessa economia foi decorrente de custos assumidos pelos pr\u00f3prios servidores, como equipamentos, insumos, rede de telefonia, internet e energia el\u00e9trica\u201d, enfatiza.<\/p>\n<p>Ele informa que existem solu\u00e7\u00f5es a serem encontradas. \u201cTeremos que encontrar uma solu\u00e7\u00e3o para isso. E tamb\u00e9m acompanhar em que medida essa nova sistem\u00e1tica vai impactar em quest\u00f5es trabalhistas, psicol\u00f3gicas e sociais\u201d, conclui.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12087&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12083&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O novo regime ser\u00e1 implantado pelo Conselho Administrativo de Defesa Econ\u00f4mica, quatro minist\u00e9rios, Secret\u00e1ria-Geral da Presid\u00eancia da Rep\u00fablica e sete ag\u00eancias reguladoras. Segundo informa\u00e7\u00f5es do Minist\u00e9rio da Economia, al\u00e9m da Controladoria-Geral da Uni\u00e3o (CGU), da Advocacia-Geral<\/p>\n","protected":false},"author":1,"featured_media":12114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12087&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12083&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O novo regime ser\u00e1 implantado pelo Conselho Administrativo de Defesa Econ\u00f4mica, quatro minist\u00e9rios, Secret\u00e1ria-Geral da Presid\u00eancia da Rep\u00fablica e sete ag\u00eancias reguladoras. Segundo informa\u00e7\u00f5es do Minist\u00e9rio da Economia, al\u00e9m da Controladoria-Geral da Uni\u00e3o (CGU), da Advocacia-Geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T21:33:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-04T21:37:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os\",\"datePublished\":\"2021-01-04T21:33:53+00:00\",\"dateModified\":\"2021-01-04T21:37:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\"},\"wordCount\":911,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\",\"name\":\"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png\",\"datePublished\":\"2021-01-04T21:33:53+00:00\",\"dateModified\":\"2021-01-04T21:37:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png\",\"width\":848,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE","og_description":"[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12087&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12083&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Flimites-consignado-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O novo regime ser\u00e1 implantado pelo Conselho Administrativo de Defesa Econ\u00f4mica, quatro minist\u00e9rios, Secret\u00e1ria-Geral da Presid\u00eancia da Rep\u00fablica e sete ag\u00eancias reguladoras. Segundo informa\u00e7\u00f5es do Minist\u00e9rio da Economia, al\u00e9m da Controladoria-Geral da Uni\u00e3o (CGU), da Advocacia-Geral","og_url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2021-01-04T21:33:53+00:00","article_modified_time":"2021-01-04T21:37:21+00:00","og_image":[{"width":848,"height":370,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png","type":"image\/png"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#article","isPartOf":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os","datePublished":"2021-01-04T21:33:53+00:00","dateModified":"2021-01-04T21:37:21+00:00","mainEntityOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/"},"wordCount":911,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/","name":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png","datePublished":"2021-01-04T21:33:53+00:00","dateModified":"2021-01-04T21:37:21+00:00","breadcrumb":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2021\/01\/65.png","width":848,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/governo-federal-adota-teletrabalho-para-servidores-de-13-orgaos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Governo federal adota teletrabalho para servidores de 13 \u00f3rg\u00e3os"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/12113"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=12113"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/12113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/12114"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=12113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=12113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=12113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}