{"id":12474,"date":"2021-06-11T18:03:46","date_gmt":"2021-06-11T21:03:46","guid":{"rendered":"https:\/\/blogdosrsiape.com\/?p=12474"},"modified":"2021-06-11T18:03:46","modified_gmt":"2021-06-11T21:03:46","slug":"reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/","title":{"rendered":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal"},"content":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12403&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12404&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]<\/p>\n<h2><strong>STF decidir\u00e1 sobre redu\u00e7\u00e3o de vantagem pessoal de servidor<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>O Supremo Tribunal Federal vai decidir se \u00e9 direito do servidor p\u00fablico a preserva\u00e7\u00e3o do valor nominal da remunera\u00e7\u00e3o, mediante fixa\u00e7\u00e3o de vantagem pessoal nominalmente identificada (VPNI), nos casos em que a administra\u00e7\u00e3o, para se adequar \u00e0 Constitui\u00e7\u00e3o Federal, modifica interpreta\u00e7\u00e3o sobre o c\u00e1lculo da vantagem remunerat\u00f3ria, ap\u00f3s longo per\u00edodo de tempo.<\/p>\n<p>&nbsp;<\/p>\n<p>A quest\u00e3o est\u00e1 sendo debatida no Recurso Extraordin\u00e1rio (RE) 1.283.360, que teve repercuss\u00e3o geral reconhecida no Plen\u00e1rio Virtual (Tema 1.145).<\/p><div id=\"ponto-3997265706\" class=\"ponto-test-placement-from-wizard-586170232-2 ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1,%20gostaria%20de%20fazer%20uma%20simula%C3%A7%C3%A3o%20de%20consignado\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"ponto-2654265674\" class=\"ponto-test-placement-from-wizard-586170232 ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1,%20gostaria%20de%20fazer%20uma%20simula%C3%A7%C3%A3o%20de%20consignado\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"ponto-3552971595\" class=\"ponto-test-placement-from-wizard-1403302673-2 ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1,%20gostaria%20de%20fazer%20uma%20simula%C3%A7%C3%A3o%20de%20consignado\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"ponto-1103721168\" class=\"ponto-test-placement-from-wizard-1403302673 ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1,%20gostaria%20de%20fazer%20uma%20simula%C3%A7%C3%A3o%20de%20consignado\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"ponto-2653477941\" class=\"ponto-conteudo-2 ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"ponto-634556675\" class=\"ponto-conteudo ponto-entity-placement\" style=\"clear: both;\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p>&nbsp;<\/p>\n<p>Continue a leitura <a href=\"https:\/\/blogdosrsiape.com\/stf-decidira-sobre-reducao-de-vantagem-pessoal-de-servidores\/\" target=\"_blank\" rel=\"noopener\">aqui.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Presidente da C\u00e2mara deseja aprovar PEC somente para futuros servidores<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Na tarde dessa \u00faltima quarta-feira (09), Arthur Lira recebeu um abaixo-assinado contra a reforma administrativa (PEC 32) de integrantes de frentes parlamentares em defesa do servi\u00e7o p\u00fablico. O documento entregue contem mais de 100 mil assinaturas de servidores e da sociedade civil contrarios a PEC.<\/p>\n<p>No encontro, o presidente da C\u00e2mara deixou claro o compromisso e a inten\u00e7\u00e3o de aprovar a reforma sem alterar as regras dos atuais funcion\u00e1rios p\u00fablicos. \u201cEle recebeu bem, mas foi taxativo ao dizer que vai aprovar a reforma para futuros servidores\u201d, disse o deputado Israel Batista (PV-DF), que preside a Frente Servir Brasil.<\/p>\n<p>Continue a leitura <a href=\"https:\/\/blogdosrsiape.com\/presidente-da-camara-deseja-aprovar-reforma-administrativa-somente-para-futuro-servidores\/\" target=\"_blank\" rel=\"noopener\">aqui.<\/a>[\/vc_column_text][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12407&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseuseguronoclick.com.br%2Fseguros%2Fodonto%2F%3F%26utm_medium%3Dseguro_amil_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_seguro_amil|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12408&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseuseguronoclick.com.br%2Fseguros%2Fodonto%2F%3F%26utm_medium%3Dseguro_amil_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_seguro_amil|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]<\/p>\n<h2><strong>Governo reduz gasto com pessoal pela primeira vez em mais de uma d\u00e9cada<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>As despesas com pessoal do governo federal ca\u00edram no ano passado, passando de R$ 286,4 bilh\u00f5es, em 2019, para R$ 285,3 bilh\u00f5es. O dado faz parte do Relat\u00f3rio Cont\u00e1bil do Tesouro Nacional, que ser\u00e1 divulgado nesta quinta-feira. Foi o primeiro recuo pelo menos desde 2009, in\u00edcio da s\u00e9rie hist\u00f3rica apresentada no levantamento.<\/p>\n<p>Como contrapartida \u00e0s transfer\u00eancias de recursos para estados e munic\u00edpios, o Congresso aprovou, a pedido do governo, a proibi\u00e7\u00e3o de reajustes de servidores das tr\u00eas esferas at\u00e9 o fim deste ano.<\/p>\n<p>A Uni\u00e3o tamb\u00e9m tem apertado a contrata\u00e7\u00e3o de pessoal e s\u00f3 deve fazer concursos ap\u00f3s a reforma administrativa.<\/p>\n<p><strong>Menor reposi\u00e7\u00e3o de aposentados<\/strong><\/p>\n<p>Para frear as despesas com sal\u00e1rios, o Minist\u00e9rio da Economia reduziu ainda a taxa de reposi\u00e7\u00e3o de servidores aposentados e digitalizou os principais servi\u00e7os p\u00fablicos.<\/p>\n<p>A conta do Tesouro \u00e9 um somat\u00f3rio da despesa bruta com ativos, inativos e pensionistas. Em 2020, as despesas com pessoal representaram o equivalente a 43,8% da receita corrente l\u00edquida do governo, n\u00famero acima de 2019.<\/p>\n<p>Isso \u00e9 justificado pelo fato de a receita do governo ter despencado por conta da Covid-19.<\/p>\n<p>Ainda segundo o Tesouro, entre 2010 e 2020, houve forte crescimento do rombo da Previd\u00eancia no INSS, passando de R$ 42,4 bilh\u00f5es, em 2010, para R$ 263,6 bilh\u00f5es, em 2020. A proje\u00e7\u00e3o atuarial do d\u00e9ficit previdenci\u00e1rio para 2022 \u00e9 de 3,50% do PIB, podendo chegar a 8,67% do PIB em 2060.<\/p>\n<p>Relat\u00f3rio divulgado antes da reforma da Previd\u00eancia estimava d\u00e9ficit de 11,64% do PIB para o mesmo ano. Ou seja, as mudan\u00e7as nas regras amenizaram, mas n\u00e3o contiveram o crescimento do rombo.<\/p>\n<p>J\u00e1 o regime dos servidores fechou 2020 com d\u00e9ficit de R$ 48,6 bilh\u00f5es. O rombo na Previd\u00eancia dos militares foi de 44,9 bilh\u00f5es.<\/p>\n<p>Fonte: O Extra[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12403&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12404&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;] STF decidir\u00e1 sobre redu\u00e7\u00e3o de vantagem pessoal de servidor &nbsp; O Supremo Tribunal Federal vai decidir se \u00e9 direito do servidor p\u00fablico a preserva\u00e7\u00e3o do valor nominal da remunera\u00e7\u00e3o, mediante fixa\u00e7\u00e3o de vantagem pessoal nominalmente<\/p>\n","protected":false},"author":1,"featured_media":11545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12403&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12404&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;] STF decidir\u00e1 sobre redu\u00e7\u00e3o de vantagem pessoal de servidor &nbsp; O Supremo Tribunal Federal vai decidir se \u00e9 direito do servidor p\u00fablico a preserva\u00e7\u00e3o do valor nominal da remunera\u00e7\u00e3o, mediante fixa\u00e7\u00e3o de vantagem pessoal nominalmente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T21:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\",\"datePublished\":\"2021-06-11T21:03:46+00:00\",\"dateModified\":\"2021-06-11T21:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\",\"url\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\",\"name\":\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif\",\"datePublished\":\"2021-06-11T21:03:46+00:00\",\"dateModified\":\"2021-06-11T21:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif\",\"width\":850,\"height\":268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/","og_locale":"pt_BR","og_type":"article","og_title":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE","og_description":"[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;12403&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;12404&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fsiape%2Fcartao-consignado-pan%2F%3F%26utm_medium%3Dcartao_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3Dblog_do_sr_siape%26utm_content%3D900x200_blog_cartao_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;] STF decidir\u00e1 sobre redu\u00e7\u00e3o de vantagem pessoal de servidor &nbsp; O Supremo Tribunal Federal vai decidir se \u00e9 direito do servidor p\u00fablico a preserva\u00e7\u00e3o do valor nominal da remunera\u00e7\u00e3o, mediante fixa\u00e7\u00e3o de vantagem pessoal nominalmente","og_url":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2021-06-11T21:03:46+00:00","og_image":[{"width":850,"height":268,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif","type":"image\/gif"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal","datePublished":"2021-06-11T21:03:46+00:00","dateModified":"2021-06-11T21:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/","url":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/","name":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif","datePublished":"2021-06-11T21:03:46+00:00","dateModified":"2021-06-11T21:03:46+00:00","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2020\/04\/resumo-da-semana-novo-1.gif","width":850,"height":268},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/reducao-de-gastos-no-governo-arthur-lira-se-manifesta-sobre-pec-e-mais-no-seu-resumo-semanal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Redu\u00e7\u00e3o de gastos no governo, Arthur Lira se manifesta sobre PEC e mais no seu resumo semanal"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/12474"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=12474"}],"version-history":[{"count":1,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/12474\/revisions"}],"predecessor-version":[{"id":12476,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/12474\/revisions\/12476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/11545"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=12474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=12474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=12474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}