{"id":13101,"date":"2022-05-26T12:21:49","date_gmt":"2022-05-26T15:21:49","guid":{"rendered":"https:\/\/blogdosrsiape.com\/?p=13101"},"modified":"2022-05-26T12:21:49","modified_gmt":"2022-05-26T15:21:49","slug":"ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/","title":{"rendered":"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano"},"content":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O ministro da Economia, Paulo Guedes, afirmou em entrevista nessa quarta-feira (25), que o reajuste salarial seria o \u00fanico recurso que encaixaria dentro do Or\u00e7amento desse ano. Na semana passada o presidente Jair Bolsonaro j\u00e1 havia recuado sobre o reajuste salarial de 5% para os servidores p\u00fablicos.<\/p>\n<p>A entrevista foi feita junto com jornalistas no F\u00f3rum Econ\u00f4mico Mundial em Davos, onde Guedes informou que o desejo de Bolsonaro seria conceder o reajuste aos policiais, por\u00e9m esse passo seria facilmente \u201cvisto como aliciamento\u201d.<\/p>\n<p>Ainda assim, o presidente continua afirmando sobre aumento diferenciado para Pol\u00edcia Federal, Departamento Penitenci\u00e1rio (Depen) e Pol\u00edcia Rodovi\u00e1ria Federal (PRF) por exemplo.<\/p><div id=\"ponto-1125887186\" class=\"ponto-conteudo ponto-entity-placement\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano\"><\/a><\/div>\n<p><strong>\u201cVoc\u00ea pode at\u00e9 dar alguma coisa, mas esquece o que ficou para tr\u00e1s. Perdas acontecem. Todo mundo perdeu no mundo inteiro. Daqui para frente, \u00e9 preciso manter? A infla\u00e7\u00e3o acumulada neste ano \u00e9 de 5% at\u00e9 agora. \u00c9 poss\u00edvel repor o funcionalismo deste ano? Sim, \u00e9 poss\u00edvel, at\u00e9 5% d\u00e1. \u00c9 por lei, em ano eleitoral, voc\u00ea s\u00f3 pode dar at\u00e9 a infla\u00e7\u00e3o e linear\u201d, explicou o ministro da Economia.<\/strong>[\/vc_column_text][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][us_image image=&#8221;13082&#8243; size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fcredito-consignado-margem-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3DRegi%25C3%25A3o%26utm_content%3Dblog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][us_image image=&#8221;13081&#8243; size=&#8221;medium&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;url:https%3A%2F%2Fseucreditonoclick.com.br%2Fcredito-consignado-margem-siape%2F%3F%26utm_medium%3Dcredito_consignado_banner%26utm_source%3DBannerBlog%26utm_campaign%3DRegi%25C3%25A3o%26utm_content%3Dblog_credito_consignado|target:_blank&#8221; el_class=&#8221;vc_hidden-md vc_hidden-lg&#8221;][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]<\/p>\n<h2><strong>Rea\u00e7\u00f5es ao reajuste salarial<\/strong><\/h2>\n<p>Na \u00faltima sexta-feira (20), Esteves Colnago, Secret\u00e1rio especial do Tesouro e Or\u00e7amento do Minist\u00e9rio da Economia, efetuou uma an\u00e1lise em que a aprova\u00e7\u00e3o de reajuste de 5% para os servidores p\u00fablicos federais pode acarretar o aumento do bloqueio do or\u00e7amento de 2022 em at\u00e9 R$ 16,2 bilh\u00f5es.<\/p>\n<p>Dentro do Or\u00e7amento da Uni\u00e3o para este ano, apenas R$ 1,7 bilh\u00e3o \u00e9 reservado para aumento salarial de servidores. Sendo assim, a administra\u00e7\u00e3o p\u00fablica seria obrigada a remanejar recursos de outras \u00e1reas para suprir o reajuste linear para todas as categorias do funcionalismo federal.<\/p>\n<p>O projeto do governo no in\u00edcio, seria direcionar recursos para agentes da PF, da PRF e do Depen. Por\u00e9m a equipe econ\u00f4mica, na \u00e9poca, se mostrou contra a medida, argumentando de que a concess\u00e3o de reajuste poderia gerar press\u00f5es de outros setores do funcionalismo.<\/p>\n<p>Com a promessa de que apenas for\u00e7as policiais fossem beneficiados com reajuste, outras categorias reagiram, o que levou o governo a temer uma greve geral em pleno ano eleitoral, quando o presidente Jair Bolsonaro tentar\u00e1 sua reelei\u00e7\u00e3o \u00e0 frente do Planalto.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row height=&#8221;auto&#8221;][vc_column][us_separator size=&#8221;small&#8221;][\/vc_column][\/vc_row][vc_row height=&#8221;auto&#8221;][vc_column][vc_column_text css_animation=&#8221;&#8221;]O ministro da Economia, Paulo Guedes, afirmou em entrevista nessa quarta-feira (25), que o reajuste salarial seria o \u00fanico recurso que encaixaria dentro do Or\u00e7amento desse ano. Na semana passada o presidente Jair Bolsonaro j\u00e1 havia recuado sobre o reajuste salarial de 5% para os servidores p\u00fablicos. A entrevista foi feita<\/p>\n","protected":false},"author":1,"featured_media":13103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes<\/title>\n<meta name=\"description\" content=\"Paulo Guedes afirma em nova entrevista que o reajuste salarial de &quot;at\u00e9 5%&quot; para servidores se encaixa no or\u00e7amento desse ano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes\" \/>\n<meta property=\"og:description\" content=\"Paulo Guedes afirma em nova entrevista que o reajuste salarial de &quot;at\u00e9 5%&quot; para servidores se encaixa no or\u00e7amento desse ano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-26T15:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png\" \/>\n\t<meta property=\"og:image:width\" content=\"783\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano\",\"datePublished\":\"2022-05-26T15:21:49+00:00\",\"dateModified\":\"2022-05-26T15:21:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\",\"name\":\"Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png\",\"datePublished\":\"2022-05-26T15:21:49+00:00\",\"dateModified\":\"2022-05-26T15:21:49+00:00\",\"description\":\"Paulo Guedes afirma em nova entrevista que o reajuste salarial de \\\"at\u00e9 5%\\\" para servidores se encaixa no or\u00e7amento desse ano.\",\"breadcrumb\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png\",\"width\":783,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes","description":"Paulo Guedes afirma em nova entrevista que o reajuste salarial de \"at\u00e9 5%\" para servidores se encaixa no or\u00e7amento desse ano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/","og_locale":"pt_BR","og_type":"article","og_title":"Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes","og_description":"Paulo Guedes afirma em nova entrevista que o reajuste salarial de \"at\u00e9 5%\" para servidores se encaixa no or\u00e7amento desse ano.","og_url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2022-05-26T15:21:49+00:00","og_image":[{"width":783,"height":441,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png","type":"image\/png"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#article","isPartOf":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano","datePublished":"2022-05-26T15:21:49+00:00","dateModified":"2022-05-26T15:21:49+00:00","mainEntityOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/","name":"Reajuste salarial para servidores \u00e9 poss\u00edvel nesse ano, segundo Guedes","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png","datePublished":"2022-05-26T15:21:49+00:00","dateModified":"2022-05-26T15:21:49+00:00","description":"Paulo Guedes afirma em nova entrevista que o reajuste salarial de \"at\u00e9 5%\" para servidores se encaixa no or\u00e7amento desse ano.","breadcrumb":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2022\/05\/djvh.png","width":783,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/ministro-da-economia-diz-que-reajuste-salarial-de-ate-5-seria-possivel-ainda-esse-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Ministro da Economia diz que reajuste salarial de \u201cat\u00e9 5%\u201d seria poss\u00edvel ainda esse ano"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/13101"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=13101"}],"version-history":[{"count":2,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/13101\/revisions"}],"predecessor-version":[{"id":13110,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/13101\/revisions\/13110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/13103"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=13101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=13101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=13101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}