{"id":1538,"date":"2015-12-16T16:00:51","date_gmt":"2015-12-16T16:00:51","guid":{"rendered":"http:\/\/www.blogdosrsiape.net\/?p=1538"},"modified":"2018-02-06T14:30:57","modified_gmt":"2018-02-06T11:30:57","slug":"qual-sera-o-dia-de-meu-pagamento-em-2016","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/qual-sera-o-dia-de-meu-pagamento-em-2016\/","title":{"rendered":"Qual ser\u00e1 o dia de meu Pagamento em 2016?"},"content":{"rendered":"<p>Qual ser\u00e1 o dia de meu pagamento em 2016? Essa \u00e9 a pergunta que muitos Servidores Ativos, Inativos e Pensionistas da Uni\u00e3o tem se feito todos os dias com tantas mudan\u00e7as previstas, dentre elas, o poss\u00edvel novo banco que ir\u00e1 assumir a maior parte da folha dos Servidores Federais, ou a poss\u00edvel e at\u00e9 prov\u00e1vel perman\u00eancia do Banco do Brasil que det\u00e9m 70% da folha atual, seguido pela Caixa Econ\u00f4mica Federal.<\/p>\n<p>O <strong><a href=\"http:\/\/www.planejamento.gov.br\/\" target=\"_blank\" rel=\"noopener\">Minist\u00e9rio do Planejamento<\/a><\/strong> anunciou que n\u00e3o haver\u00e1 altera\u00e7\u00e3o no calend\u00e1rio de pagamentos dos servidores da Uni\u00e3o. Em 2016, o sal\u00e1rio de mais de 1,37 milh\u00e3o de servidores ativos, inativos e pensionistas do governo federal vai continuar sendo pago no primeiro dia \u00fatil do m\u00eas, ou no segundo dia \u00fatil no caso de algumas autarquias. A regra tamb\u00e9m dever\u00e1 ser mantida para o 13\u00ba sal\u00e1rio, que sair\u00e1 em duas parcelas: uma em 1\u00ba de julho, com o pagamento relativo a junho, e a outra no contracheque referente a novembro, com o dep\u00f3sito programado para 1\u00ba de dezembro. O Minist\u00e9rio informou ainda que a inscri\u00e7\u00e3o para venda da folha dos servidores a institui\u00e7\u00f5es financeiras interessadas vai at\u00e9 o dia 2 de janeiro de 2016<\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n<p>Publicado por Extra Globo<\/p><div id=\"ponto-870933024\" class=\"ponto-conteudo ponto-entity-placement\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Qual ser\u00e1 o dia de meu Pagamento em 2016?\"><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qual ser\u00e1 o dia de meu pagamento em 2016? Essa \u00e9 a pergunta que muitos Servidores Ativos, Inativos e Pensionistas da Uni\u00e3o tem se feito todos os dias com tantas mudan\u00e7as previstas, dentre elas, o poss\u00edvel novo banco que ir\u00e1 assumir a maior parte da folha dos Servidores Federais, ou a poss\u00edvel e at\u00e9 prov\u00e1vel<\/p>\n","protected":false},"author":1,"featured_media":1098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66],"tags":[2034,2071,2152,2158],"class_list":["post-1538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salarios","tag-salarios","tag-segep","tag-siape","tag-sigepe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE<\/title>\n<meta name=\"description\" content=\"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-16T16:00:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-06T11:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Qual ser\u00e1 o dia de meu Pagamento em 2016?\",\"datePublished\":\"2015-12-16T16:00:51+00:00\",\"dateModified\":\"2018-02-06T11:30:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\"},\"wordCount\":219,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg\",\"keywords\":[\"Sal\u00e1rios\",\"SEGEP\",\"Siape\",\"SIGEPE\"],\"articleSection\":[\"Sal\u00e1rios\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\",\"url\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\",\"name\":\"Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg\",\"datePublished\":\"2015-12-16T16:00:51+00:00\",\"dateModified\":\"2018-02-06T11:30:57+00:00\",\"description\":\"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Pagamento de Servidores P\u00fablicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual ser\u00e1 o dia de meu Pagamento em 2016?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE","description":"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE","og_description":"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o","og_url":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2015-12-16T16:00:51+00:00","article_modified_time":"2018-02-06T11:30:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg","type":"image\/jpeg"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Qual ser\u00e1 o dia de meu Pagamento em 2016?","datePublished":"2015-12-16T16:00:51+00:00","dateModified":"2018-02-06T11:30:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/"},"wordCount":219,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg","keywords":["Sal\u00e1rios","SEGEP","Siape","SIGEPE"],"articleSection":["Sal\u00e1rios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/","url":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/","name":"Qual ser\u00e1 o dia de meu Pagamento em 2016? - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg","datePublished":"2015-12-16T16:00:51+00:00","dateModified":"2018-02-06T11:30:57+00:00","description":"O Minist\u00e9rio do Planejamento Or\u00e7amento e Gest\u00e3o confirmou a perman\u00eancia do calend\u00e1rio de Pagamento da Folha dos Servidores P\u00fablicos da Uni\u00e3o","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/08\/shutterstock_189709589.jpg","width":1000,"height":1000,"caption":"Pagamento de Servidores P\u00fablicos"},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/qual-sera-o-dia-de-meu-pagamento-em-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Qual ser\u00e1 o dia de meu Pagamento em 2016?"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1538"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=1538"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/1098"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=1538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=1538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=1538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}