{"id":1578,"date":"2016-01-15T13:24:06","date_gmt":"2016-01-15T13:24:06","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=1578"},"modified":"2017-09-20T18:04:57","modified_gmt":"2017-09-20T15:04:57","slug":"1578","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/1578\/","title":{"rendered":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado"},"content":{"rendered":"<p><span style=\"color: #333333;\">Desde 01 de Janeiro de 2016 os bancos passaram a exigir a gera\u00e7\u00e3o da senha de consigna\u00e7\u00e3o \u00e0 consignat\u00e1ria para averba\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito consignado para os servidores p\u00fablicos federais. A medida visa diminuir o n\u00famero atual de reclama\u00e7\u00f5es registradas nos \u00d3rg\u00e3os e at\u00e9 Justi\u00e7a, com reclamat\u00f3rias de fraude na contrata\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"color: #333333;\">O Procedimento embora simples, ainda causa certo transtorno aos servidor ativos, inativos e pensionistas que desconhecem o portal<\/span> <strong><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"http:\/\/www.siapenet.gov.br\/portal\/Servico\/Central.asp\" target=\"_blank\" rel=\"noopener\">SIGEP<\/a>E<\/span><span style=\"color: #3366ff;\">, <\/span><\/strong><span style=\"color: #333333;\">plataforma utilizada para acessar o ultimo contracheque, agendar f\u00e9rias, gerenciar sua consigna\u00e7\u00f5es, gerar a senha de autoriza\u00e7\u00e3o aos bancos e mais algumas funcionalidades; ou seja, o RH Virtual do Servidor.<\/span><\/p>\n<p><span style=\"color: #333333;\">O primeiro acesso exige que o usu\u00e1rio j\u00e1 possua um e-mail cadastrado em sua UPAG, pois todos os passos seguintes emitir\u00e3o senhas e c\u00f3digos enviados \u00e0 esse e-mail at\u00e9 concluir a autentica\u00e7\u00e3o e libera\u00e7\u00e3o de acesso.<\/span><\/p>\n<p><span style=\"color: #333333;\">Uma vez gerada, a senha lhe dar\u00e1 a conveni\u00eancia de acessar suas informa\u00e7\u00f5es de RH a qualquer momento e at\u00e9 atrav\u00e9s de seu Celular e Tablet com o SIGEPE Mobile, aplicativo que possibilita acessar todas funcionalidades do portal.<\/span><\/p>\n<p><span style=\"color: #333333;\">o \u00danico banco que n\u00e3o oficializou a exig\u00eancia at\u00e9 o momento \u00e9 o Banco do Brasil, que det\u00e9m cerca de 70% da folha de pagamento dos Servidores Federais Ativos, Inativos e Pensionistas. No entanto, \u00e9 prov\u00e1vel que passe a exigi-l\u00e1 nos pr\u00f3ximos dias.<\/span><\/p>\n<p><span style=\"color: #333333;\">Empresas especializadas na intermedia\u00e7\u00e3o da venda do Cr\u00e9dito Consignado j\u00e1 se adaptaram para oferecer ao cliente, al\u00e9m da habitual consultoria financeira, um suporte na gera\u00e7\u00e3o dos acessos a esse portal.<\/span><\/p>\n<p><span style=\"color: #333333;\">Nosso patrocinador abaixo, \u00e9 especializado no atendimento \u00e0 Servidores Federais Ativos, Inativos e Pensionistas e oferece tamb\u00e9m apoio na gera\u00e7\u00e3o do acesso e senha, atrav\u00e9s de seus Consultores e V\u00eddeo explicativo.<\/span><\/p>\n<figure id=\"attachment_1259\" aria-describedby=\"caption-attachment-1259\" style=\"width: 129px\" class=\"wp-caption aligncenter\"><a href=\"seucreditonoclick.com.br\/\" rel=\"attachment wp-att-1259\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1259\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2015\/09\/novo-logo-seucreditonoclick.png\" alt=\"Senha Siape, Senha SIGEPE, Senha SEGEP\" width=\"129\" height=\"155\" \/><\/a><figcaption id=\"caption-attachment-1259\" class=\"wp-caption-text\"><span style=\"color: #339966;\">Seu Cr\u00e9dito no Click<\/span><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Desde 01 de Janeiro de 2016 os bancos passaram a exigir a gera\u00e7\u00e3o da senha de consigna\u00e7\u00e3o \u00e0 consignat\u00e1ria para averba\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito consignado para os servidores p\u00fablicos federais. A medida visa diminuir o n\u00famero atual de reclama\u00e7\u00f5es registradas nos \u00d3rg\u00e3os e at\u00e9 Justi\u00e7a, com reclamat\u00f3rias de fraude na contrata\u00e7\u00e3o. O Procedimento embora<\/p>\n","protected":false},"author":1,"featured_media":2544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[623,2071,2152,2158],"class_list":["post-1578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-credito-consignado","tag-consignado","tag-segep","tag-siape","tag-sigepe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/1578\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"Desde 01 de Janeiro de 2016 os bancos passaram a exigir a gera\u00e7\u00e3o da senha de consigna\u00e7\u00e3o \u00e0 consignat\u00e1ria para averba\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito consignado para os servidores p\u00fablicos federais. A medida visa diminuir o n\u00famero atual de reclama\u00e7\u00f5es registradas nos \u00d3rg\u00e3os e at\u00e9 Justi\u00e7a, com reclamat\u00f3rias de fraude na contrata\u00e7\u00e3o. O Procedimento embora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/1578\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-15T13:24:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-20T15:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado\",\"datePublished\":\"2016-01-15T13:24:06+00:00\",\"dateModified\":\"2017-09-20T15:04:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png\",\"keywords\":[\"Consignado\",\"SEGEP\",\"Siape\",\"SIGEPE\"],\"articleSection\":[\"CR\u00c9DITO CONSIGNADO\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/1578\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/\",\"url\":\"https:\/\/blogdosrsiape.com\/1578\/\",\"name\":\"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png\",\"datePublished\":\"2016-01-15T13:24:06+00:00\",\"dateModified\":\"2017-09-20T15:04:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/1578\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png\",\"width\":848,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/1578\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/1578\/","og_locale":"pt_BR","og_type":"article","og_title":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE","og_description":"Desde 01 de Janeiro de 2016 os bancos passaram a exigir a gera\u00e7\u00e3o da senha de consigna\u00e7\u00e3o \u00e0 consignat\u00e1ria para averba\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito consignado para os servidores p\u00fablicos federais. A medida visa diminuir o n\u00famero atual de reclama\u00e7\u00f5es registradas nos \u00d3rg\u00e3os e at\u00e9 Justi\u00e7a, com reclamat\u00f3rias de fraude na contrata\u00e7\u00e3o. O Procedimento embora","og_url":"https:\/\/blogdosrsiape.com\/1578\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2016-01-15T13:24:06+00:00","article_modified_time":"2017-09-20T15:04:57+00:00","og_image":[{"width":848,"height":370,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png","type":"image\/png"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/1578\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/1578\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado","datePublished":"2016-01-15T13:24:06+00:00","dateModified":"2017-09-20T15:04:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/1578\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/1578\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png","keywords":["Consignado","SEGEP","Siape","SIGEPE"],"articleSection":["CR\u00c9DITO CONSIGNADO"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/1578\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/1578\/","url":"https:\/\/blogdosrsiape.com\/1578\/","name":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/1578\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/1578\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png","datePublished":"2016-01-15T13:24:06+00:00","dateModified":"2017-09-20T15:04:57+00:00","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/1578\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/1578\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/1578\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2017\/09\/blog-imagens-28.png","width":848,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/1578\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Bancos exigem senha de consigna\u00e7\u00e3o para opera\u00e7\u00f5es de Cr\u00e9dito Consignado"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1578"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=1578"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/2544"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=1578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=1578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=1578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}