{"id":1783,"date":"2016-07-08T19:20:40","date_gmt":"2016-07-08T16:20:40","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=1783"},"modified":"2022-04-26T16:01:55","modified_gmt":"2022-04-26T19:01:55","slug":"1783","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/1783\/","title":{"rendered":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados"},"content":{"rendered":"<p>55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados &#8211; Um estudo realizado pelo Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC <span class=\"premium-tip\">Brasil<\/span>) e pela Confedera\u00e7\u00e3o Nacional de Dirigentes Lojistas (CNDL), divulgado nesta quinta-feira (9), apontou que 54,7% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem os juros cobrado quando h\u00e1 atraso no pagamento da fatura.<\/p>\n<p>E a cobran\u00e7a pode ser alta. <a href=\"http:\/\/g1.globo.com\/economia\/seu-dinheiro\/noticia\/2016\/06\/juros-do-cartao-tem-maior-taxa-desde-1995-e-do-cheque-especial-de-1999.html\" target=\"_blank\" rel=\"noopener\">A taxa de juros no cart\u00e3o de cr\u00e9dito para pessoa f\u00edsica voltou a atingir o maior n\u00edvel desde 1995<\/a>, a 15,12% ao m\u00eas e 441,76% ao ano, segundo a Associa\u00e7\u00e3o Nacional de Executivos de Finan\u00e7as, Administra\u00e7\u00e3o e Contabilidade (Anefac).<\/p>\n<p>Mais de um quarto (26,5%) desses consumidores n\u00e3o analisaram as taxas que s\u00e3o cobradas nas opera\u00e7\u00f5es ao adquirem o cart\u00e3o de cr\u00e9dito. A maior parte dos desinformados tem idade entre 18 e 34 anos (61,6%).<\/p>\n<p>A pesquisa tamb\u00e9m mostrou que o parcelamento \u00e9 um recurso bastante comum entre os que usam o cart\u00e3o de cr\u00e9dito \u2013 69% deles parcelam suas compras pelo menos uma vez ao m\u00eas. Em m\u00e9dia, os entrevistados afirmam possuir quatro parcelas de cart\u00e3o n\u00e3o quitadas.<\/p>\n<p>Sete em cada dez (76,2%) consumidores avaliam o cart\u00e3o de cr\u00e9dito como algo positivo em suas vidas. Quase a metade (47%) dos usu\u00e1rios dessa forma de pagamento, no entanto, n\u00e3o realizam um controle efetivo das compras que s\u00e3o feitas no cart\u00e3o, seja por apenas conferirem a fatura \u2013 sem analis\u00e1-la de fato \u2013 ou porque fazem o controle somente de cabe\u00e7a, sem qualquer rigor ou controle sistem\u00e1tico.<\/p>\n<p>Para Marcela Kawauti, economista-chefe do <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/spc\/\" target=\"_blank\" rel=\"noopener\">SPC Brasil<\/a>, os cuidados com os gastos do cart\u00e3o devem ser constantes.<\/p>\n<p>\u201c\u00c9 fundamental acompanhar a fatura do cart\u00e3o ao longo do m\u00eas e n\u00e3o apenas quando j\u00e1 estiver fechada, pois a\u00ed ser\u00e1 tarde para avaliar se os gastos foram excessivos\u201d, explicou.<\/p>\n<p><strong>OPORTUNIDADE EXCLUSIVA PARA SERVIDORES FEDERAIS\u00a0 &#8211; Por outro lado, desde 23\/11\/2016 esta dispon\u00edvel margem extra, de 5,00% do Salario dos Servidores Federais para o <a href=\"https:\/\/www.seucreditonoclick.com.br\/nossas-solucoes-de-credito\/cartao-consignado-siape\/\" target=\"_blank\" rel=\"noopener\">CART\u00c3O DE CREDITO CONSIGNADO<\/a>. \u00c9 a oportunidade \u00danica de unir todas as facilidades e praticidades do Cart\u00e3o Convencional, cujo Juro \u00e9 estratosf\u00e9rico, para um cart\u00e3o cujo juro \u00e9 4 (quatro) vezes menor!<\/strong><\/p>\n<p>Publicado por G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados &#8211; Um estudo realizado pelo Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC Brasil) e pela Confedera\u00e7\u00e3o Nacional de Dirigentes Lojistas (CNDL), divulgado nesta quinta-feira (9), apontou que 54,7% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem os juros cobrado quando h\u00e1 atraso no pagamento da fatura. E<\/p>\n","protected":false},"author":1,"featured_media":1642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,21],"tags":[452],"class_list":["post-1783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cartao-de-credito-2","category-credito-2","tag-cartao-de-credito"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE<\/title>\n<meta name=\"description\" content=\"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/1783\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/1783\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-08T16:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T19:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados\",\"datePublished\":\"2016-07-08T16:20:40+00:00\",\"dateModified\":\"2022-04-26T19:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/\"},\"wordCount\":388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg\",\"keywords\":[\"cart\u00e3o de cr\u00e9dito\"],\"articleSection\":[\"Cart\u00e3o de Cr\u00e9dito\",\"Cr\u00e9dito\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/1783\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/\",\"url\":\"https:\/\/blogdosrsiape.com\/1783\/\",\"name\":\"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg\",\"datePublished\":\"2016-07-08T16:20:40+00:00\",\"dateModified\":\"2022-04-26T19:01:55+00:00\",\"description\":\"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/1783\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg\",\"width\":728,\"height\":410,\"caption\":\"Usu\u00e1rios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/1783\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE","description":"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/1783\/","og_locale":"pt_BR","og_type":"article","og_title":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE","og_description":"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande","og_url":"https:\/\/blogdosrsiape.com\/1783\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2016-07-08T16:20:40+00:00","article_modified_time":"2022-04-26T19:01:55+00:00","og_image":[{"width":728,"height":410,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg","type":"image\/jpeg"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/1783\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/1783\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados","datePublished":"2016-07-08T16:20:40+00:00","dateModified":"2022-04-26T19:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/1783\/"},"wordCount":388,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/1783\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg","keywords":["cart\u00e3o de cr\u00e9dito"],"articleSection":["Cart\u00e3o de Cr\u00e9dito","Cr\u00e9dito"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/1783\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/1783\/","url":"https:\/\/blogdosrsiape.com\/1783\/","name":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/1783\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/1783\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg","datePublished":"2016-07-08T16:20:40+00:00","dateModified":"2022-04-26T19:01:55+00:00","description":"A maior parte dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito, desconhece o juros praticado pelos bancos e administradoras. Com isso, a grande","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/1783\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/1783\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/1783\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2016\/03\/cartao_de_credito_-_foto_ilustrativa.jpg","width":728,"height":410,"caption":"Usu\u00e1rios"},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/1783\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"55% dos usu\u00e1rios de cart\u00e3o de cr\u00e9dito desconhecem juros cobrados"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1783"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=1783"}],"version-history":[{"count":1,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1783\/revisions"}],"predecessor-version":[{"id":13020,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/1783\/revisions\/13020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/1642"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=1783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=1783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=1783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}