{"id":7159,"date":"2018-08-02T23:52:37","date_gmt":"2018-08-02T20:52:37","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=7159"},"modified":"2018-11-30T21:45:53","modified_gmt":"2018-11-30T18:45:53","slug":"viagem-castelos-deserto-jordania","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/viagem-castelos-deserto-jordania\/","title":{"rendered":"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia"},"content":{"rendered":"<p>Al\u00e9m de pontos tur\u00edsticos como Petra e Mar Morto, a Jord\u00e2nia tem muitos outros atrativos para oferecer aos seus visitantes. Os Castelos do Deserto s\u00e3o destinos que mostram a arte arquitet\u00f4nica isl\u00e2mica, remanescentes dos s\u00e9culos 7 e 8, que at\u00e9 hoje est\u00e3o bem preservadas no meio de desertos.<\/p>\n<h3>Por que &#8220;Castelos&#8221;?<\/h3>\n<p>As constru\u00e7\u00f5es foram apelidadas de castelos devido \u00e0 import\u00e2ncia e magnitude que tinham na \u00e9poca mas, na verdade, esses complexos possu\u00edam diversas finalidades. Alguns eram postos de paradas para caravanas, pavilh\u00f5es, centros comerciais e at\u00e9 mesmo fortalezas.<\/p>\n<p>Grande parte do que est\u00e1 bem preservado pode ser encontrado na cidade de Am\u00e3, ao leste e ao sul.<\/p><div id=\"ponto-3025160219\" class=\"ponto-conteudo ponto-entity-placement\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia\"><\/a><\/div>\n<h3>Qasr Amra<\/h3>\n<p>O mais famoso \u00e9 o castelo de Qasr Amra, que foi tombado pela Unesco como Patrim\u00f4nio da Humanidade. Est\u00e1 localizado a 85 km de Am\u00e3 e, em tempos antigos, servia como uma fortaleza e resid\u00eancia para os califas Om\u00edadas.<\/p>\n<p>A c\u00fapula e a casa de banho desse Qasr s\u00e3o a parte principal do pal\u00e1cio. Os afrescos e mosaicos que molduram o local contam a hist\u00f3ria de derrotas dos califas e mostram as divindades que cultuavam.<\/p>\n<p>Qasr Amra est\u00e1 em uma localiza\u00e7\u00e3o exposta a eros\u00f5es, devido as tempestades de areia e inunda\u00e7\u00f5es que acontecem sazonalmente. Para isso foi criada uma medida que tem colaborado para evitar essas corros\u00f5es e desgastes. O plantio de \u00e1rvores ao leste e ao norte do local ajudam a reduzir o impacto da aridez do deserto, enquanto os diques, a oeste, desviam a inunda\u00e7\u00e3o causada pelas chuvas.<\/p>\n<p>O Qasr Al-Azraq \u00e9 o mais diferenciado entre todos os castelos do deserto. Por ter sido constru\u00eddo com basalto, ele \u00e9 mais escuro que os demais e acaba por se destacar.<\/p>\n<p>Al\u00e9m disso, o castelo possui um o\u00e1sis que o tornava um ponto estrat\u00e9gico, j\u00e1 que era um dos poucos locais que possuem uma fonte de \u00e1gua doce. Devido a nascente, o local era frequentado principalmente por militares e foi usado como fortaleza durante a Revolta \u00c1rabe.<\/p>\n<p>O escritor Thomas Edward Lawrence visitou o local e o citou em seu livro \u201cOs Sete Pilares da Sabedoria\u201d.<\/p>\n<p>O Qasr Al Karak \u00e9 conhecido principalmente por ter sido constru\u00eddo e dominado na \u00e9poca das Cruzadas. A fortaleza gigantesca de pedra est\u00e1 bem preservada at\u00e9 os dias atuais. Os guias que mostram o local tem muito orgulho da regi\u00e3o e s\u00e3o muito bem dispostos a explicar a hist\u00f3ria de Karak.<\/p>\n<p>N\u00e3o esque\u00e7a de levar uma lanterna antes de entrar dentro do castelo, por ser um pouco subterr\u00e2neo e possuir t\u00faneis, o local n\u00e3o \u00e9 t\u00e3o iluminado.<\/p>\n<p>Fonte: <a href=\"http:\/\/www.qualviagem.com.br\/castelos-do-deserto-rota-diferencial-na-jordania\/\">Qual Viagem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os castelos da Jord\u00e2nia foram pontos estrat\u00e9gicos para batalhas medievais.<\/p>\n","protected":false},"author":1,"featured_media":7857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[4019,4017,4018,2152,2519,2158,2473,2601],"class_list":["post-7159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-viagens","tag-arquitetura","tag-castelojordania","tag-patrimoniohistorico","tag-siape","tag-sigac","tag-sigepe","tag-viajar","tag-world"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE<\/title>\n<meta name=\"description\" content=\"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE\" \/>\n<meta property=\"og:description\" content=\"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-02T20:52:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-30T18:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia\",\"datePublished\":\"2018-08-02T20:52:37+00:00\",\"dateModified\":\"2018-11-30T18:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png\",\"keywords\":[\"arquitetura\",\"castelojordania\",\"patrimoniohistorico\",\"Siape\",\"SIGAC\",\"SIGEPE\",\"Viajar\",\"world\"],\"articleSection\":[\"Turismo \/ Viagens\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\",\"url\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\",\"name\":\"Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png\",\"datePublished\":\"2018-08-02T20:52:37+00:00\",\"dateModified\":\"2018-11-30T18:45:53+00:00\",\"description\":\"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png\",\"width\":840,\"height\":380,\"caption\":\"Castelo - Jordania\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE","description":"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/","og_locale":"pt_BR","og_type":"article","og_title":"Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE","og_description":"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.","og_url":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2018-08-02T20:52:37+00:00","article_modified_time":"2018-11-30T18:45:53+00:00","og_image":[{"width":840,"height":380,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png","type":"image\/png"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia","datePublished":"2018-08-02T20:52:37+00:00","dateModified":"2018-11-30T18:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png","keywords":["arquitetura","castelojordania","patrimoniohistorico","Siape","SIGAC","SIGEPE","Viajar","world"],"articleSection":["Turismo \/ Viagens"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/","url":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/","name":"Castelos do deserto - Rota diferencial na Jord\u00e2nia - BLOG DO SR SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png","datePublished":"2018-08-02T20:52:37+00:00","dateModified":"2018-11-30T18:45:53+00:00","description":"A arte arquitet\u00f4nica isl\u00e2mica remanescente dos s\u00e9culos 7 e 8, continuam preservadas no meio de desertos, pronta para ser visitada.","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/08\/castelos-jordania.png","width":840,"height":380,"caption":"Castelo - Jordania"},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/viagem-castelos-deserto-jordania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Castelos do deserto &#8211; Rota diferencial na Jord\u00e2nia"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/7159"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=7159"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/7159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/7857"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=7159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=7159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=7159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}