{"id":7248,"date":"2018-05-08T16:03:45","date_gmt":"2018-05-08T13:03:45","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=7248"},"modified":"2018-12-05T17:33:02","modified_gmt":"2018-12-05T14:33:02","slug":"viagem-destinos-corpus-christi","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/viagem-destinos-corpus-christi\/","title":{"rendered":"10 melhores destinos para o feriado de Corpus Christi 2018"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text css_animation=&#8221;slideInLeft&#8221;]O feriado <strong>Corpus Christi<\/strong> 2018 vai ser daqueles perfeitos para programar a t\u00e3o esperada viagem! Vai dar para relaxar na praia, fazer passeios ecol\u00f3gicos, conhecer paisagens ex\u00f3ticas, fazer uma imers\u00e3o cultural e comer muito bem. Tem pra todos os gostos!<\/p>\n<h3>Quando?<\/h3>\n<p>31 de maio a 3 de junho de 2018<\/p>\n<p>Na d\u00favida de para onde viajar no feriad\u00e3o de <strong>Corpus Christi<\/strong> 2018? Aproveite a folga e renove as energias!<\/p>\n<p>Veja a seguir 10 dicas de destinos no Brasil e na Am\u00e9rica do Sul:<\/p>\n<h3><\/h3>\n<h3>Porto Seguro, Bahia<\/h3>\n<figure id=\"attachment_7249\" aria-describedby=\"caption-attachment-7249\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7249 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/portoseguro.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/portoseguro.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/portoseguro-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7249\" class=\"wp-caption-text\">Al\u00e9m das belas praias, Porto Seguro tem variadas riquezas culturais e arquitet\u00f4nicas<\/figcaption><\/figure>\n<p>Considerado o ber\u00e7o do Brasil, Porto Seguro \u00e9 adorado pela galera mais jovem (tem agito 24 horas por dia). Mas tamb\u00e9m por quem procura belas paisagens para descansar e repor as energias. S\u00e3o quil\u00f4metros de fal\u00e9sias coloridas, recifes de corais e vegeta\u00e7\u00e3o de Mata Atl\u00e2ntica, al\u00e9m das riquezas culturais, arquitet\u00f4nicas e naturais que garantiram os t\u00edtulos de Patrim\u00f4nio Hist\u00f3rico Nacional e de Patrim\u00f4nio Natural da Humanidade.<\/p>\n<p>Dif\u00edcil vai ser escolher em qual praia montar a barraca \u2013 se na agitada Taperapu\u00e3 (famosa tamb\u00e9m pelo R\u00e9veillon) ou nos famosos de distritos de Arraial d\u00b4Ajuda ou de Trancoso, com suas piscinas naturais de \u00e1guas morninhas.<\/p>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/BPS\/2018-05-31\/2018-06-03\/2\/0\/0\/NA\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=da16d04b7c15493392717c154291dfdd&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7264\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner1.png\" alt=\"Corpus\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner1.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner1-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner1-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Tiradentes, Minas Gerais<\/h3>\n<figure id=\"attachment_7250\" aria-describedby=\"caption-attachment-7250\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7250 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/tiradentes.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/tiradentes.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/tiradentes-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7250\" class=\"wp-caption-text\">As ruas de pedras de Tiradentes ficam ainda mais charmosas \u00e0 noite<\/figcaption><\/figure>\n<p>\u00c9 a mais charmosa das cidades hist\u00f3ricas de Minas Gerais. Tiradentes \u00e9 daqueles destinos para ser explorado a p\u00e9 e bem devagar. Nada melhor para poder apreciar todos os detalhes arquitet\u00f4nicos dos patrim\u00f4nios hist\u00f3ricos que se espalham pelas ruas de pedras da cidade, em uma verdadeira aula pr\u00e1tica de hist\u00f3ria.<\/p>\n<p>Outra op\u00e7\u00e3o para curtir o cen\u00e1rio encantador, rodeado pelas montanhas da Serra de S\u00e3o Jos\u00e9, \u00e9 andar de charrete ou mesmo passear de \u201cmaria-fuma\u00e7a\u201d (at\u00e9 a vizinha S\u00e3o Jo\u00e3o del Rei), \u00e0s margens do Rio das Mortes. Sem esquecer de parar para observar as igrejas do s\u00e9culo 18. Com obras de Aleijadinho, o artesanato original e as del\u00edcias gastron\u00f4micas s\u00e3o passeios imperd\u00edveis.<\/p>\n<h3><a href=\"http:\/\/www.booking.com\/searchresults.pt-br.html?aid=391895&amp;sid=b16cad699a4d8d08288c78ee20280ed8&amp;sb=1&amp;src=searchresults&amp;src_elem=sb&amp;error_url=https%3A%2F%2Fwww.booking.com%2Fsearchresults.pt-br.html%3Faid%3D391895%3Bsid%3Db16cad699a4d8d08288c78ee20280ed8%3Bcheckin_month%3D5%3Bcheckin_monthday%3D31%3Bcheckin_year%3D2018%3Bcheckout_month%3D6%3Bcheckout_monthday%3D3%3Bcheckout_year%3D2018%3Bclass_interval%3D1%3Bdest_id%3D-677399%3Bdest_type%3Dcity%3Bdtdisc%3D0%3Bfrom_sf%3D1%3Bgroup_adults%3D2%3Bgroup_children%3D0%3Binac%3D0%3Bindex_postcard%3D0%3Blabel_click%3Dundef%3Bno_rooms%3D1%3Boffset%3D0%3Bpostcard%3D0%3Braw_dest_type%3Dcity%3Broom1%3DA%252CA%3Bsb_price_type%3Dtotal%3Bsearch_selected%3D1%3Bsrc%3Dindex%3Bsrc_elem%3Dsb%3Bss%3DUbatuba%252C%2520Estado%2520de%2520S%25C3%25A3o%2520Paulo%252C%2520Brasil%3Bss_all%3D0%3Bss_raw%3DUbatuba%3Bssb%3Dempty%3Bsshis%3D0%3Bssne_untouched%3DCampos%2520do%2520Jord%25C3%25A3o%3Buser_changed_date%3D1%26%3B&amp;ss=Tiradentes%2C+Minas+Gerais%2C+Brasil&amp;ssne=Ubatuba&amp;ssne_untouched=Ubatuba&amp;city=-677399&amp;checkin_year=2018&amp;checkin_month=5&amp;checkin_monthday=31&amp;checkout_year=2018&amp;checkout_month=6&amp;checkout_monthday=3&amp;group_adults=2&amp;group_children=0&amp;no_rooms=1&amp;from_sf=1&amp;user_changed_date=0&amp;ss_raw=Tiradentes&amp;ac_position=0&amp;ac_langcode=xb&amp;dest_id=-676172&amp;dest_type=city&amp;place_id_lat=-21.111294&amp;place_id_lon=-44.168297&amp;search_pageview_id=769f58ae963400d0&amp;search_selected=true&amp;search_pageview_id=769f58ae963400d0&amp;ac_suggestion_list_length=5&amp;ac_suggestion_theme_list_length=0\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7265\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner2.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner2.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner2-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner2-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>B\u00fazios, Rio de Janeiro<\/h3>\n<figure id=\"attachment_7251\" aria-describedby=\"caption-attachment-7251\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7251 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/buzios.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/buzios.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/buzios-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7251\" class=\"wp-caption-text\">A praia da Ferradurinha \u00e9 uma das mais cobi\u00e7adas de B\u00fazios<\/figcaption><\/figure>\n<p>Um destino que nunca sai de moda e serve perfeito para o feriado de <strong>Corpus Christi<\/strong>: B\u00fazios, uma das joias da Regi\u00e3o dos Lagos do Rio de Janeiro. Apelida de a \u201cSaint-Tropez brasileira\u201d, virou munic\u00edpio s\u00f3 em 1995, mas h\u00e1 mais de cinco d\u00e9cadas vem atraindo turistas do mundo todo com suas maravilhosas paisagens naturais.<\/p>\n<p>Se o clima ainda \u00e9 de cidade pequena, a estrutura para receber os visitantes \u00e9 de primeira, com restaurantes e hot\u00e9is sofisticados, vida noturna agitada e com\u00e9rcio variado. Sem falar das cerca de 20 praias, uma para cada gosto e estilo, seja para surfar, mergulhar, fazer festa ou apenas para relaxar e fazer nada.<\/p>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/SDU\/2018-05-31\/2018-06-03\/2\/0\/0\/BZC\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=55115c8c370843dd9acb961b11af807b&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7267\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner3.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner3.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner3-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner3-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Montevid\u00e9u, Uruguai<\/h3>\n<figure id=\"attachment_7252\" aria-describedby=\"caption-attachment-7252\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7252 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/uruguai.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/uruguai.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/uruguai-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7252\" class=\"wp-caption-text\">A Plaza Independencia \u00e9 um dos cart\u00f5es-postais de Montevid\u00e9u<\/figcaption><\/figure>\n<p>Os quatro dias de folga poder\u00e3o ser a desculpa perfeita para uma viagem para o exterior. Tudo bem que n\u00e3o ser\u00e1 para t\u00e3o longe, mas Montevid\u00e9u vai caber no bolso e no calend\u00e1rio para aproveitar o feriado de <strong>Corpus Christi<\/strong> 2018.<\/p>\n<p>A capital uruguaia \u00e9 puro charme, hist\u00f3ria e cultura, com atra\u00e7\u00f5es e op\u00e7\u00f5es de passeios para gostos variados. Dos pr\u00e9dios hist\u00f3ricos na Ciudad Vieja e em torno da Plaza Independ\u00eancia a um passeio \u00e0 beira do Rio del Plata, sem faltar uma parada nos deliciosos restaurantes do Mercado del Puerto.<\/p>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/MVD\/2018-05-31\/2018-06-03\/2\/0\/0\/NA\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=df53e718407b4541afdf02c9baedd367&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7268\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner4.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner4.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner4-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner4-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Foz do Igua\u00e7u, Paran\u00e1<\/h3>\n<figure id=\"attachment_7253\" aria-describedby=\"caption-attachment-7253\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7253 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/foz.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/foz.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/foz-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7253\" class=\"wp-caption-text\">Um passeio de barco leva o visitante bem pertinho das imponentes Cataratas do Igua\u00e7u<\/figcaption><\/figure>\n<p>Foz do Igua\u00e7u \u00e9 a orgulhosa sede do representante brasileiro na lista das 7 Novas Maravilhas do Mundo e dos Patrim\u00f4nios Mundiais da Humanidade: as Cataratas do Igua\u00e7u. Vale dedicar pelo menos um dia inteiro para explorar o conjunto de 275 quedas d\u00b4\u00e1gua que chegam a 90 metros de altura, al\u00e9m dos parques naturais ao redor, com direito a passeios de barco e helic\u00f3ptero.<\/p>\n<p>Quando estiver em Foz, que fica bem no meio da tr\u00edplice fronteira Brasil-Argentina-Paraguai, n\u00e3o pode deixar de aproveitar tamb\u00e9m para se divertir nos cassinos e fazer umas comprinhas nos freeshops dos hermanos vizinhos.<\/p>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/IGU\/2018-05-31\/2018-06-03\/2\/0\/0\/NA\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=f412c812dfaa4f25b35a4f21cb09624c&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7269\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner5.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner5.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner5-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner5-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Pantanal, Mato Grosso\/Mato Grosso do Sul<\/h3>\n<figure id=\"attachment_7256\" aria-describedby=\"caption-attachment-7256\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7256 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/pantanal.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/pantanal.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/pantanal-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7256\" class=\"wp-caption-text\">A fauna presente no Pantanal Matogrossense \u00e9 das mais variadas \u2013 destaque, claro, para a on\u00e7a-pintada<\/figcaption><\/figure>\n<p>Outro Patrim\u00f4nio Natural Mundial, o Pantanal \u00e9 um dos cen\u00e1rios naturais mais fascinantes do Brasil. S\u00e3o cerca de 250 mil metros quadrados de \u00e1rea total, que vai do sul do Mato Grosso ao noroeste do Mato Grosso do Sul, al\u00e9m de ter \u00e1reas no norte do Paraguai e leste da Bol\u00edvia (por l\u00e1 \u00e9 chamado de \u201cchaco boliviano\u201d).<\/p>\n<p>A dica \u00e9 agendar passeios com guias especializados para poder ter contato com as exuberantes flora e fauna (que podem incluir a on\u00e7a-pintada e a capivara), fazer trilhas ecol\u00f3gicas ou fazer uma pescaria relaxante.<\/p>\n<h3><a href=\"https:\/\/suaviagemnoclick.com.br\/pacotes\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7271\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner6.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner6.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner6-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner6-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Santiago, Chile<\/h3>\n<figure id=\"attachment_7257\" aria-describedby=\"caption-attachment-7257\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7257 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/santiago-1.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/santiago-1.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/santiago-1-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7257\" class=\"wp-caption-text\">O centro de Santiago guarda in\u00fameros atrativos, incluindo o majestoso Cerro Santa Luc\u00eda<\/figcaption><\/figure>\n<p>Chegou feriad\u00e3o! Que tal arrumar as malas em dire\u00e7\u00e3o a um dos principais destinos tur\u00edsticos da Am\u00e9rica do Sul? Santiago ostenta um pacote de atra\u00e7\u00f5es que agrada ao mesmo tempo aventureiros, gourmets e f\u00e3s de hist\u00f3ria e cultura.<\/p>\n<p>Aos p\u00e9s da Cordilheira dos Andes, a capital chilena tem paisagens hist\u00f3ricas, morros e montanhas para fazer trekking, muitas vin\u00edcolas e esta\u00e7\u00f5es de esqui (ativas geralmente entre os meses de junho e setembro), e tantas mais atividades para ocupar o itiner\u00e1rio de viagem.<\/p>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/SCL\/2018-05-31\/2018-06-03\/2\/0\/0\/NA\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=0da686ea3766416b8d9cae35fc279429&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7273\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner8.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner8.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner8-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner8-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Canoa Quebrada, Cear\u00e1<\/h3>\n<figure id=\"attachment_7258\" aria-describedby=\"caption-attachment-7258\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7258 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/canoaquebrada.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/canoaquebrada.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/canoaquebrada-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7258\" class=\"wp-caption-text\">Dunas, fal\u00e9sias e \u00e1guas claras comp\u00f5em a paisagem paradis\u00edaca de Canoa Quebrada<\/figcaption><\/figure>\n<p>A pouco mais de 160 km de Fortaleza, o pequeno munic\u00edpio de Aracati sedia uma pacata aldeia de pescadores que foi descoberta pelos hippies nos anos 1970 e desde ent\u00e3o ganhou fama mundial. Canoa Quebrada continua atraindo e encantando multid\u00f5es com suas dunas, \u00e1guas esverdeadas e fal\u00e9sias avermelhadas de at\u00e9 30m acima do n\u00edvel do mar.<\/p>\n<p>O clima descontra\u00eddo e relaxante reina por l\u00e1. Especialmente nas v\u00e1rias prainhas da regi\u00e3o. Podem ser visitadas por meio de passeios de jangada, ou vistas do alto atrav\u00e9s de um voo de parapente cheio de adrenalina.<\/p>\n<h3><\/h3>\n<h3><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/FOR\/2018-05-31\/2018-06-03\/2\/0\/0\/CQ2\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=e554b293e4164be4ba424f0850cdc528&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7278\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner9.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner9.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner9-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner9-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Ubatuba, S\u00e3o Paulo<\/h3>\n<figure id=\"attachment_7259\" aria-describedby=\"caption-attachment-7259\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7259 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/ubatuba.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/ubatuba.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/ubatuba-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7259\" class=\"wp-caption-text\">Ubatuba \u00e9 o destino perfeito para quem procura belas paisagens naturais para descansar e relaxar<\/figcaption><\/figure>\n<p>Ubatuba \u00e9 um verdadeiro para\u00edso natural! \u00c9 a ideia perfeita para o feriado de <strong>Corpus Christi<\/strong> para quem gosta de praia. Afinal, s\u00e3o nada menos que 102 praias espalhadas por 100 quil\u00f4metros de \u00e1rea!<\/p>\n<p>Dif\u00edcil vai ser escolher quais praias visitar e que atividades praticar. Vale lembrar que a cidade tem a alcunha de \u201ccapital do surfe\u201d. Mas as lindas paisagens compostas de \u00e1guas azuis e verdes, cachoeiras, ilhas para mergulhar e cost\u00f5es de Mata Atl\u00e2ntica v\u00e3o render tamb\u00e9m passeios de escuna e trilhas ecol\u00f3gicas inesquec\u00edveis.<\/p>\n<h3><a href=\"http:\/\/www.booking.com\/searchresults.pt-br.html?aid=391895&amp;sid=b16cad699a4d8d08288c78ee20280ed8&amp;sb=1&amp;src=index&amp;src_elem=sb&amp;error_url=https%3A%2F%2Fwww.booking.com%2Findex.pt-br.html%3Faid%3D391895%3Bsid%3Db16cad699a4d8d08288c78ee20280ed8%3Bsb_price_type%3Dtotal%26%3B&amp;ss=Ubatuba%2C+Estado+de+S\u00e3o+Paulo%2C+Brasil&amp;ssne=Campos+do+Jord\u00e3o&amp;ssne_untouched=Campos+do+Jord\u00e3o&amp;checkin_year=2018&amp;checkin_month=5&amp;checkin_monthday=31&amp;checkout_year=2018&amp;checkout_month=6&amp;checkout_monthday=3&amp;no_rooms=1&amp;group_adults=2&amp;group_children=0&amp;from_sf=1&amp;user_changed_date=1&amp;ss_raw=Ubatuba&amp;ac_position=0&amp;ac_langcode=xb&amp;dest_id=-677399&amp;dest_type=city&amp;place_id_lat=-23.435575&amp;place_id_lon=-45.073124&amp;search_pageview_id=8c51589b9b9e001c&amp;search_selected=true&amp;search_pageview_id=8c51589b9b9e001c&amp;ac_suggestion_list_length=5&amp;ac_suggestion_theme_list_length=0\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7279\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner10.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner10.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner10-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner10-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h3>Manaus, Amazonas<\/h3>\n<figure id=\"attachment_7260\" aria-describedby=\"caption-attachment-7260\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7260 size-full\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/frutas.png\" alt=\"Corpus\" width=\"700\" height=\"380\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/frutas.png 700w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/frutas-300x163.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7260\" class=\"wp-caption-text\">Pelas ruas ou nos mercados, aproveite para provar as frutas t\u00edpicas que s\u00f3 Manaus tem para oferecer<\/figcaption><\/figure>\n<p>Manaus costuma ser o ponto de partida para quem quer explorar a floresta a Floresta Amaz\u00f4nica. Mas a capital do Amazonas tamb\u00e9m tem atra\u00e7\u00f5es suficientes para garantir uma \u00f3tima viagem no feriado da Semana Santa.<\/p>\n<p>Entre os passeios ecol\u00f3gicos imperd\u00edveis por l\u00e1, est\u00e3o o tour de barco at\u00e9 o encontro dos rios Negro e Solim\u00f5es ou de canoa pelos igarap\u00e9s. Fora da \u00e1gua, o visitante vai se encantar com as suntuosas constru\u00e7\u00f5es da \u00e9poca do apogeu do Ciclo da Borracha, como o Teatro Amazonas. E tamb\u00e9m se deliciar com os aromas e sabores da culin\u00e1ria t\u00edpica amazonense, onde reinam os peixes, frutas ex\u00f3ticas e temperos como o tucupi.<\/p>\n<p><a href=\"http:\/\/www.e-agencias.com.br\/ag68060\/cp\/search\/SAO\/MAO\/2018-05-31\/2018-06-03\/2\/0\/0\/NA\/2018-05-31\/2018-06-03\/2\/true\/NA\/0#\/search?trip=0d09155268e34e87bd61305d15938ada&amp;hsort=&amp;fsort=&amp;bsort=&amp;sel=hotel&amp;hp=1&amp;fp=1&amp;bp=1&amp;flow=\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7280\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner11.png\" alt=\"\" width=\"600\" height=\"143\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner11.png 840w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner11-300x71.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/banner11-768x183.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>[vc_facebook type=&#8221;button_count&#8221; css_animation=&#8221;zoomInLeft&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<p>Agora voc\u00ea j\u00e1 sabe onde passar o feriado de <strong>Corpus Christi<\/strong>! Junte a fam\u00edlia e os amigos e fa\u00e7a um passeio inesquec\u00edvel! Estes locais, com certeza, ser\u00e3o \u00f3timos para descansar e aproveitar cada segundo!<\/p>\n<p><a href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/category\/turismo-viagens\/\">Tenham<\/a> todos uma excelente ter\u00e7a-feira!<\/p>\n<p>Boa viagem!<\/p>\n<p>&nbsp;<\/p>\n<p><em>Fonte: <a href=\"https:\/\/blog.mundi.com.br\/2018\/03\/09\/feriado-corpus-christi\/\">Mundi Blog<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!<\/p>\n","protected":false},"author":1,"featured_media":7262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[381,2921,978,979,2128,2135,2152,2519,2158,2470],"class_list":["post-7248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-viagens","tag-brasil","tag-corpus-christi","tag-feriado","tag-ferias","tag-servidores","tag-servidores-publicos-federais","tag-siape","tag-sigac","tag-sigepe","tag-viagem"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 melhores destinos para o feriado de Corpus Christi 2018<\/title>\n<meta name=\"description\" content=\"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 melhores destinos para o feriado de Corpus Christi 2018\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-08T13:03:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-05T14:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"10 melhores destinos para o feriado de Corpus Christi 2018\",\"datePublished\":\"2018-05-08T13:03:45+00:00\",\"dateModified\":\"2018-12-05T14:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\"},\"wordCount\":1542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png\",\"keywords\":[\"Brasil\",\"Corpus Christi\",\"Feriado\",\"f\u00e9rias\",\"Servidores\",\"SERVIDORES P\u00daBLICOS FEDERAIS\",\"Siape\",\"SIGAC\",\"SIGEPE\",\"Viagem\"],\"articleSection\":[\"Turismo \/ Viagens\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\",\"url\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\",\"name\":\"10 melhores destinos para o feriado de Corpus Christi 2018\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png\",\"datePublished\":\"2018-05-08T13:03:45+00:00\",\"dateModified\":\"2018-12-05T14:33:02+00:00\",\"description\":\"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!\",\"breadcrumb\":{\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png\",\"width\":840,\"height\":380,\"caption\":\"Corpus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 melhores destinos para o feriado de Corpus Christi 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 melhores destinos para o feriado de Corpus Christi 2018","description":"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/","og_locale":"pt_BR","og_type":"article","og_title":"10 melhores destinos para o feriado de Corpus Christi 2018","og_description":"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!","og_url":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2018-05-08T13:03:45+00:00","article_modified_time":"2018-12-05T14:33:02+00:00","og_image":[{"width":840,"height":380,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png","type":"image\/png"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#article","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"10 melhores destinos para o feriado de Corpus Christi 2018","datePublished":"2018-05-08T13:03:45+00:00","dateModified":"2018-12-05T14:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/"},"wordCount":1542,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png","keywords":["Brasil","Corpus Christi","Feriado","f\u00e9rias","Servidores","SERVIDORES P\u00daBLICOS FEDERAIS","Siape","SIGAC","SIGEPE","Viagem"],"articleSection":["Turismo \/ Viagens"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/","url":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/","name":"10 melhores destinos para o feriado de Corpus Christi 2018","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage"},"image":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png","datePublished":"2018-05-08T13:03:45+00:00","dateModified":"2018-12-05T14:33:02+00:00","description":"J\u00e1 sabe onde ir\u00e1 passar o feriado de Corpus Christi? N\u00e3o se preocupe, temos 10 destinos ideais pra voc\u00ea se divertir e descansar viajando!","breadcrumb":{"@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/05\/capa-1.png","width":840,"height":380,"caption":"Corpus"},{"@type":"BreadcrumbList","@id":"https:\/\/blogdosrsiape.com\/viagem-destinos-corpus-christi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"10 melhores destinos para o feriado de Corpus Christi 2018"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/7248"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=7248"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/7248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/7262"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=7248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=7248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=7248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}