{"id":8674,"date":"2018-12-19T22:32:10","date_gmt":"2018-12-19T19:32:10","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=8674"},"modified":"2020-01-29T20:06:08","modified_gmt":"2020-01-29T22:06:08","slug":"lewandowski-reajuste-2019-servidores","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/","title":{"rendered":"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"destaque\" class=\"img-destaque banner-textos\">Publicidade<a href=\"https:\/\/seucreditonoclick.com.br\/#destaque_materia_blog\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-full wp-image-3433\" style=\"max-width: 900px;\" src=\"\/wp-content\/uploads\/2018\/11\/credito-inst.gif\" alt=\"Credito SIAPE | SIGAC\" width=\"100%\" \/><\/a><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][sem_destaque]-200[\/sem_destaque]<\/p>\n<h3>Ministro suspendeu medida provis\u00f3ria que adiava o reajuste para 2020. Impacto previsto com a medida \u00e9 de R$ 4,7 bilh\u00f5es.<\/h3>\n<p>O ministro Ricardo Lewandowski, do Supremo Tribunal Federal (STF), determinou nesta quarta-feira (19) a suspens\u00e3o de medida provis\u00f3ria que adia o reajuste de servidores p\u00fablicos de 2019 para 2020.<\/p><div id=\"ponto-3163168982\" class=\"ponto-conteudo ponto-entity-placement\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019\"><\/a><\/div>\n<p>Com isso, o <strong>reajuste de 209 mil servidores civis ativos e 163 mil inativos<\/strong> do governo federal, com <strong>percentuais de 4,5% a 6,3% de aumento<\/strong> na remunera\u00e7\u00e3o, ter\u00e3o que ser pagos no ano que vem. A previs\u00e3o de impacto, segundo a a\u00e7\u00e3o, \u00e9 de <strong>R$ 4,7 bilh\u00f5es em 2019<\/strong>.<\/p>\n<p>Ainda cabe recurso, que dever\u00e1 ser analisado pelo presidente do STF, Dias Toffoli, por conta do recesso do Judici\u00e1rio, que come\u00e7a nesta quinta (20).<\/p>\n<p>Lewandowski \u00e9 relator de cinco a\u00e7\u00f5es de entidades contra a <strong>MP 849\/2018<\/strong>, que adia os reajustes. Al\u00e9m disso, a MP tamb\u00e9m cancela o aumento concedido para os <strong>124 mil<\/strong> cargos em comiss\u00e3o, fun\u00e7\u00f5es de confian\u00e7a e gratifica\u00e7\u00f5es existentes no Executivo.<\/p>\n<p>As a\u00e7\u00f5es afirmam que a medida \u00e9 inconstitucional porque \u00e9 proibido ao chefe do Executivo editar norma com o mesmo conte\u00fado de MP que j\u00e1 foi rejeitada ou tenha perdido efic\u00e1cia.<\/p>\n<p>Lewandowski lembrou que no fim do ano passado suspendeu outra MP que adiava o reajuste de 2018 para 2019. E citou que, em maio deste ano, arquivou a a\u00e7\u00e3o porque a MP perdeu a efic\u00e1cia ao n\u00e3o ter sido votada pelo Congresso.<\/p>\n<p>Lewandowski afirmou que o Congresso reconheceu a proibi\u00e7\u00e3o de reedi\u00e7\u00e3o de medida com o mesmo teor de outra rejeitada ou que tenha perdido efic\u00e1cia, conforme prev\u00ea o par\u00e1grafo 10 do artigo 62 da Constitui\u00e7\u00e3o.<\/p>\n<h3>Previsto em lei<\/h3>\n<p>Na decis\u00e3o de 41 p\u00e1ginas, <strong>Lewandowski destacou que o reajuste j\u00e1 estava previsto em lei<\/strong> para vigorar e que os servidores atingidos t\u00eam carreiras &#8220;essenciais&#8221; ao funcionamento do Estado.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"destaque\" class=\"img-destaque banner-textos\">Publicidade<a href=\"https:\/\/seucreditonoclick.com.br\/consig-express\/#destaque_materia_blog\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-full wp-image-3433\" style=\"max-width: 900px;\" src=\"\/wp-content\/uploads\/2018\/09\/banner-credito.jpg\" alt=\"Credito Consignado SIAPE | SIGAC\" width=\"100%\" \/><\/a><\/div>\n<p>[\/vc_column_text][vc_column_text css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;]&#8221;As diversas carreiras de servidores p\u00fablicos federais siape \/ sigac alcan\u00e7adas pela medida provis\u00f3ria atacada, dentre as quais se encontram carreiras t\u00edpicas de Estado \u2013 essenciais ao seu pr\u00f3prio funcionamento \u2013, experimentar\u00e3o a suspens\u00e3o da parcela restante de reajustes j\u00e1 concedidos por leis aprovadas pelos representantes da soberania popular, reunidos no Congresso Nacional, respondendo a uma tempestiva e regular provoca\u00e7\u00e3o do Executivo&#8221;, diz a decis\u00e3o. Ele destacou que os aumentos foram aprovados pelo Congresso e sancionados pelo Pal\u00e1cio do Planalto.<\/p>\n<p>O ministro viu a tentativa de adiar os pagamentos como <strong>&#8220;quebra do princ\u00edpio da leg\u00edtima confian\u00e7a e da seguran\u00e7a jur\u00eddica, as sim como a vulnera\u00e7\u00e3o de direitos j\u00e1 incorporados a o patrim\u00f4nio dos servidores&#8221;.<\/strong> E considerou uma &#8220;discrimina\u00e7\u00e3o injustificada e injustific\u00e1vel&#8221;.<\/p>\n<p>Lewandowski considerou ainda que <strong>reeditar MP com o mesmo<\/strong> tema viola a Constitui\u00e7\u00e3o. &#8220;For\u00e7oso concluir pela exist\u00eancia da plausibilidade jur\u00eddica do pedido, em face da constata\u00e7\u00e3o de que a reedi\u00e7\u00e3o do ato normativo questionado, \u00e0 primeira vista, viola o texto constitucional e a jurisprud\u00eancia firmada por esta Corte&#8221;, escreveu o ministro.<\/p>\n<p>O ministro determinou que o adiamento dos pagamentos deve ser suspenso at\u00e9 que o plen\u00e1rio julgue a quest\u00e3o de maneira definitiva para &#8220;resguardar direitos dos servidores&#8221;. Ainda n\u00e3o h\u00e1 previs\u00e3o de data para julgamento.<\/p>\n<p>&#8220;Com a proximidade dos recessos parlamentar e judici\u00e1rio, faz-se necess\u00e1rio o deferimento da medida acauteladora, a fim de que se suspenda a efic\u00e1cia de toda a <strong>Medida Provis\u00f3ria 849\/2018,<\/strong> de modo a resguardar os direitos dos servidores p\u00fablicos federais e prevenir a consuma\u00e7\u00e3o de pr\u00e1tica, aparentemente, inconstitucional, at\u00e9 que o Plen\u00e1rio deste Supremo Tribunal possa debru\u00e7ar-se de maneira vertical e definitiva sobre as alega\u00e7\u00f5es trazidas aos autos&#8221;, afirmou.<\/p>\n<p>Leia tamb\u00e9m:\u00a0<a href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/orcamento-e-gestao\/carreiras-servidores-reducao-cargos\/\">COLNAGO SUGERE REDUZIR N\u00daMERO DE CARREIRAS FEDERAIS PARA MENOS DE 20<\/a><\/p>\n<p>Fonte: <a href=\"https:\/\/g1.globo.com\/politica\/noticia\/2018\/12\/19\/lewandowski-obriga-governo-a-pagar-reajuste-de-servidores-em-2019-impacto-previsto-e-de-r-47-bi.ghtml\">G1<\/a><\/p>\n<h3><strong>CR\u00c9DITO CONSIGNADO SEM BUROCRACIA em at\u00e9 2 HORAS na sua CONTA.<\/strong><\/h3>\n<p><strong>Se voc\u00ea tamb\u00e9m vai receber aumento em 2019 e deseja consultar as suas op\u00e7\u00f5es de cr\u00e9dito, deixe o seu nome e telefone no formul\u00e1rio abaixo, para entrarmos em contato.<\/strong>[\/vc_column_text][contact-form-7 id=&#8221;8755&#8243; title=&#8221;Deixe seus dados para ser contatado&#8221;][vc_row_inner css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;][vc_column_inner width=&#8221;2\/12&#8243; css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;][vc_single_image source=&#8221;external_link&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;bounceIn&#8221; custom_src=&#8221;\/wp-content\/themes\/blogsiape\/img\/icon_notifications.jpg&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;10\/12&#8243; css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;][vc_column_text css_animation=&#8221;slideInRight&#8221; css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221; el_class=&#8221;cor_preta&#8221;]<\/p>\n<h2 class=\"cor_preta\" align=\"left\">Receba as not\u00edcias antes dos demais Assinantes!<\/h2>\n<p class=\"cor_preta\" align=\"left\">Clique para ativar as notifica\u00e7\u00f5es e receba antes de serem publicadas<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MP que adiava o reajuste do servidor p\u00fablico federal foi derrubado por ministro Lewandowski<\/p>\n","protected":false},"author":1,"featured_media":8684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[64],"tags":[1927,2135,2152,2519,2158],"class_list":["post-8674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reajuste","tag-reajuste-salarial","tag-servidores-publicos-federais","tag-siape","tag-sigac","tag-sigepe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape<\/title>\n<meta name=\"description\" content=\"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape\" \/>\n<meta property=\"og:description\" content=\"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T19:32:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-29T22:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019\",\"datePublished\":\"2018-12-19T19:32:10+00:00\",\"dateModified\":\"2020-01-29T22:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\"},\"wordCount\":859,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg\",\"keywords\":[\"Reajuste Salarial\",\"SERVIDORES P\u00daBLICOS FEDERAIS\",\"Siape\",\"SIGAC\",\"SIGEPE\"],\"articleSection\":[\"Reajuste\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\",\"name\":\"REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg\",\"datePublished\":\"2018-12-19T19:32:10+00:00\",\"dateModified\":\"2020-01-29T22:06:08+00:00\",\"description\":\"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.\",\"breadcrumb\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg\",\"width\":840,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape","description":"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/","og_locale":"pt_BR","og_type":"article","og_title":"REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape","og_description":"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.","og_url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2018-12-19T19:32:10+00:00","article_modified_time":"2020-01-29T22:06:08+00:00","og_image":[{"width":840,"height":380,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg","type":"image\/jpeg"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#article","isPartOf":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019","datePublished":"2018-12-19T19:32:10+00:00","dateModified":"2020-01-29T22:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/"},"wordCount":859,"commentCount":1,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg","keywords":["Reajuste Salarial","SERVIDORES P\u00daBLICOS FEDERAIS","Siape","SIGAC","SIGEPE"],"articleSection":["Reajuste"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/","name":"REAJUSTE DE SERVIDORES SER\u00c1 PAGO EM 2019 - Blog do Sr Siape","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg","datePublished":"2018-12-19T19:32:10+00:00","dateModified":"2020-01-29T22:06:08+00:00","description":"Reajuste de 4,5% a 6,3% de aumento na remunera\u00e7\u00e3o, garantidos para 209 mil servidores sigac \/ sigepe ativos e 163 mil inativos do governo federal.","breadcrumb":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2018\/12\/lewandovski.jpg","width":840,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/lewandowski-reajuste-2019-servidores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"LEWANDOWSKI OBRIGA GOVERNO A PAGAR REAJUSTE DE SERVIDORES EM 2019"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/8674"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=8674"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/8674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/8684"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=8674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=8674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=8674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}