{"id":9245,"date":"2019-04-30T00:06:38","date_gmt":"2019-04-29T21:06:38","guid":{"rendered":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/?p=9245"},"modified":"2020-01-29T20:06:33","modified_gmt":"2020-01-29T22:06:33","slug":"servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/","title":{"rendered":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;]<\/p>\n<div id=\"destaque\" class=\"img-destaque banner-textos\">Publicidade<a href=\"https:\/\/seuseguronoclick.com.br\/seguros\/cotacao-auto\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8871\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/01\/banner-seguro-ret.jpg\" alt=\"\" width=\"900\" height=\"100\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/01\/banner-seguro-ret.jpg 900w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/01\/banner-seguro-ret-300x33.jpg 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/01\/banner-seguro-ret-768x85.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/div>\n<p>[\/vc_column_text][vc_column_text fnt_size_h2=&#8221;24&#8243; fnt_size_h3=&#8221;20&#8243;]<em><strong>Servidores p\u00fablicos federais que ganham acima de R$ 10 mil mensais ser\u00e3o os mais atingidos pela al\u00edquota progressiva que o governo pretende criar com a reforma da Previd\u00eancia.<\/strong><\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"17\" data-block-id=\"2\">\n<p>Dados da equipe econ\u00f4mica enviados ao Congresso Nacional mostram que esse grupo, que recebe o equivalente a pelo menos dez sal\u00e1rios m\u00ednimos por m\u00eas, ser\u00e1 respons\u00e1vel por R$ 21,3 bilh\u00f5es do aumento de R$ 27,7 bilh\u00f5es na arrecada\u00e7\u00e3o esperada em dez anos com a mudan\u00e7a nas al\u00edquotas.<\/p>\n<p>O governo deixou claro que o aumento das al\u00edquotas dos servidores Federais do SIAPE, \u00e9 necess\u00e1rio para bancar a redu\u00e7\u00e3o das contribui\u00e7\u00f5es dos trabalhadores vinculados ao INSS, que representar\u00e1 uma ren\u00fancia de R$ 28,4 bilh\u00f5es no mesmo per\u00edodo.<\/p>\n<p>A proposta do governo institui um sistema de al\u00edquotas progressivas, que v\u00e3o de 7,5% a 22%, conforme o sal\u00e1rio do servidor. A cobran\u00e7a incide sobre faixas de renda. Na pr\u00e1tica, a contribui\u00e7\u00e3o de 22% incidir\u00e1 s\u00f3 sobre a parcela do sal\u00e1rio que superar os R$ 39 mil mensais &#8211; s\u00f3 1.142 servidores se enquadram nessa situa\u00e7\u00e3o, como j\u00e1 informou o Estad\u00e3o\/Broadcast.<\/p>\n<p>Pelos dados do governo, no per\u00edodo de uma d\u00e9cada, R$ 11,2 bilh\u00f5es vir\u00e3o das al\u00edquotas cobradas de quem ganha entre R$ 10 mil e R$ 20 mil. Outros R$ 9,9 bilh\u00f5es ser\u00e3o arrecadados sobre quem recebe de R$ 20 mil a R$ 39,2 mil. Quem ganha acima do teto remunerat\u00f3rio atual, de R$ 39,2 mil, dar\u00e1 contribui\u00e7\u00e3o de R$ 234,2 milh\u00f5es.<\/p>\n<p>Categorias do funcionalismo classificam a medida de &#8220;confisco&#8221; e pressionam deputados a barrar essa e outras mudan\u00e7as que est\u00e3o na proposta. O secret\u00e1rio de Previd\u00eancia do Minist\u00e9rio da Economia, Leonardo Rolim, tem participado de conversas com parlamentares e n\u00e3o v\u00ea resist\u00eancia dos congressistas \u00e0 altera\u00e7\u00e3o nas al\u00edquotas.<\/p>\n<\/div>\n<p>[\/vc_column_text][vc_column_text css=&#8221;%7B%22default%22%3A%5B%5D%7D&#8221;]<\/p><div id=\"ponto-3453353335\" class=\"ponto-conteudo ponto-entity-placement\"><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=558006071111&#038;text=Ol%C3%A1%2C+gostaria+de+fazer+uma+cota%C3%A7%C3%A3o+de+seguro+auto+para+servidores\" aria-label=\"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia\"><\/a><\/div>\n<div id=\"destaque\" class=\"img-destaque banner-textos\">Publicidade<a href=\"https:\/\/seucreditonoclick.com.br\/credito-consignado-com-selfie\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9232\" src=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/Banner-selfie-1.png\" alt=\"\" width=\"900\" height=\"100\" srcset=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/Banner-selfie-1.png 900w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/Banner-selfie-1-300x33.png 300w, https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/Banner-selfie-1-768x85.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/div>\n<p>[\/vc_column_text][vc_column_text]&#8221;\u00c9 dif\u00edcil um parlamentar defender uma pessoa que ganhe mais de R$ 39 mil, dizer que sobre os R$ 300 que ele ganha acima, por exemplo, cobrar al\u00edquota de 22% \u00e9 injusto&#8221;, diz.<\/p>\n<p>Ele lembra que a m\u00e9dia de sal\u00e1rios do funcionalismo \u00e9 bem maior que o pr\u00f3prio teto dos benef\u00edcios dos trabalhadores da iniciativa privada, que contribuem ao INSS e recebem no m\u00e1ximo R$ 5.839,45.<\/p>\n<p>No Executivo, a m\u00e9dia salarial dos servidores na ativa \u00e9 de R$ 9,7 mil mensais. Os valores s\u00e3o ainda maiores no Legislativo (R$ 20,2 mil), no Judici\u00e1rio (R$ 14,2 mil) e no Minist\u00e9rio P\u00fablico (R$ 14,7 mil).<\/p>\n<p>Quem ingressou no funcionalismo at\u00e9 2013 pode se aposentar com benef\u00edcios maiores que o teto do INSS. S\u00e3o esses servidores que est\u00e3o na mira da equipe econ\u00f4mica, pois o gasto que a Uni\u00e3o tem para bancar essas aposentadorias \u00e9 elevado. &#8220;Aqueles que v\u00e3o se aposentar com um benef\u00edcio um pouco maior v\u00e3o pagar um pouco mais&#8221;, diz Rolim.<\/p>\n<p>O secret\u00e1rio faz dele pr\u00f3prio um exemplo da medida. Servidor concursado da C\u00e2mara dos Deputados, Rolim poderia, pelas regras atuais, se aposentar em 2025, aos 59 anos, com benef\u00edcio de R$ 39,3 mil mesmo n\u00e3o tendo contribu\u00eddo com 11% sobre esse valor durante toda sua carreira. Com a reforma, ele precisar\u00e1 trabalhar at\u00e9 os 65 anos e pagar\u00e1 uma al\u00edquota maior.<\/p>\n<p>&#8220;Vou pagar 16,8% (de al\u00edquota efetiva). E te digo, ainda est\u00e1 barato para o custo da minha aposentadoria. Para tornar o meu sistema sustent\u00e1vel, equilibrado, seria muito mais&#8221;, diz.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"https:\/\/www.estadao.com.br\/\">O Estado de S. Paulo.<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!<\/p>\n","protected":false},"author":1,"featured_media":9249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[74],"tags":[],"class_list":["post-9245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servidores-publicos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE<\/title>\n<meta name=\"description\" content=\"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE\" \/>\n<meta property=\"og:description\" content=\"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Sr. SIAPE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T21:06:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-29T22:06:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Sr.Siape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Sr.Siape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\"},\"author\":{\"name\":\"Blog Sr.Siape\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"headline\":\"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia\",\"datePublished\":\"2019-04-29T21:06:38+00:00\",\"dateModified\":\"2020-01-29T22:06:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg\",\"articleSection\":[\"Servidores P\u00fablicos Federais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\",\"name\":\"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE\",\"isPartOf\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg\",\"datePublished\":\"2019-04-29T21:06:38+00:00\",\"dateModified\":\"2020-01-29T22:06:33+00:00\",\"description\":\"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!\",\"breadcrumb\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg\",\"width\":730,\"height\":356},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/blogdosrsiape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogdosrsiape.com\/#website\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"name\":\"Blog do sr. SIAPE\",\"description\":\"SIAPE Servidor Federal\",\"publisher\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogdosrsiape.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blogdosrsiape.com\/#organization\",\"name\":\"Blog do sr. SIAPE\",\"url\":\"https:\/\/blogdosrsiape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png\",\"width\":287,\"height\":116,\"caption\":\"Blog do sr. SIAPE\"},\"image\":{\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR\",\"https:\/\/www.instagram.com\/srsiape\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"Blog Sr.Siape\",\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE","description":"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/","og_locale":"pt_BR","og_type":"article","og_title":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE","og_description":"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!","og_url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/","og_site_name":"Blog do Sr. SIAPE","article_publisher":"https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","article_published_time":"2019-04-29T21:06:38+00:00","article_modified_time":"2020-01-29T22:06:33+00:00","og_image":[{"width":730,"height":356,"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg","type":"image\/jpeg"}],"author":"Blog Sr.Siape","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blog Sr.Siape","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#article","isPartOf":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/"},"author":{"name":"Blog Sr.Siape","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"headline":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia","datePublished":"2019-04-29T21:06:38+00:00","dateModified":"2020-01-29T22:06:33+00:00","mainEntityOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg","articleSection":["Servidores P\u00fablicos Federais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/","name":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia - Blog do Sr. SIAPE","isPartOf":{"@id":"https:\/\/blogdosrsiape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg","datePublished":"2019-04-29T21:06:38+00:00","dateModified":"2020-01-29T22:06:33+00:00","description":"Servidores SIGAC que ganham acima de de R$ 10 mil pagar\u00e3o mais impostos! O que vai mudar pra voc\u00ea? Descubra Agora!","breadcrumb":{"@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2019\/04\/profissoes-em-alta-para-futuro-guia-completo-2020-730x356.jpg","width":730,"height":356},{"@type":"BreadcrumbList","@id":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/servidores-federais-quem-ganham-mais-de-r-10-mil-serao-os-mais-afetados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogdosrsiape.com\/"},{"@type":"ListItem","position":2,"name":"Servidores federais que ganham mais de R$ 10 mil ser\u00e3o os mais afetados na Previd\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/blogdosrsiape.com\/#website","url":"https:\/\/blogdosrsiape.com\/","name":"Blog do sr. SIAPE","description":"SIAPE Servidor Federal","publisher":{"@id":"https:\/\/blogdosrsiape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdosrsiape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogdosrsiape.com\/#organization","name":"Blog do sr. SIAPE","url":"https:\/\/blogdosrsiape.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/","url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","contentUrl":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-content\/uploads\/sites\/2\/2024\/10\/logo-1.png","width":287,"height":116,"caption":"Blog do sr. SIAPE"},"image":{"@id":"https:\/\/blogdosrsiape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogsrsiape\/?locale=pt_BR","https:\/\/www.instagram.com\/srsiape\/"]},{"@type":"Person","@id":"https:\/\/blogdosrsiape.com\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"Blog Sr.Siape","sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/9245"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/comments?post=9245"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/posts\/9245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media\/9249"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/media?parent=9245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/categories?post=9245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/blogsrsiape\/wp-json\/wp\/v2\/tags?post=9245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}