{"id":8450,"date":"2019-12-17T12:28:35","date_gmt":"2019-12-17T14:28:35","guid":{"rendered":"https:\/\/blogdosrsiape.com\/?p=8450"},"modified":"2020-03-11T17:40:48","modified_gmt":"2020-03-11T20:40:48","slug":"bonito-ms-o-espetaculo-da-natureza","status":"publish","type":"post","link":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/","title":{"rendered":"Bonito &#8211; MS &#8220;o espet\u00e1culo da natureza&#8221;"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image vc_hidden-sm vc_hidden-xs align_none\"><a target=\"_blank\" href=\"https:\/\/suaviagemnoclick.com\/pacotes-promocionais\/?&amp;utm_medium=viagem_pacotes_banner&amp;utm_source=BannerBlog&amp;utm_campaign=blog_do_sr_siape&amp;utm_content=900x200_blog_viagem_pacotes\" rel=\"noopener\" aria-label=\"Link\" class=\"w-image-h\"><img decoding=\"async\" width=\"970\" height=\"250\" src=\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/paoctes-verao-900x200-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/paoctes-verao-900x200-1.png 970w, https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/paoctes-verao-900x200-1-300x77.png 300w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/a><\/div><div class=\"w-image vc_hidden-md vc_hidden-lg align_none\"><a target=\"_blank\" href=\"https:\/\/suaviagemnoclick.com\/pacotes-promocionais\/?&amp;utm_medium=viagem_pacotes_banner&amp;utm_source=BannerBlog&amp;utm_campaign=blog_do_sr_siape&amp;utm_content=500x500_blog_viagem_pacotes\" rel=\"noopener\" aria-label=\"Link\" class=\"w-image-h\"><img decoding=\"async\" width=\"306\" height=\"199\" src=\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2020\/01\/feriados-em-2020.gif\" class=\"attachment-large size-large\" alt=\"\" \/><\/a><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\" ><div class=\"wpb_wrapper\"><h3><strong><em>Conhe\u00e7a um pouco mais de Bonito no MS e confira tudo que h\u00e1 de bom neste destino.<\/em><\/strong><\/h3>\n<p>Um dos lugares mais lindos do Brasil, n\u00e3o poderia ter outro nome sem ser \u201cBonito\u201d. Um para\u00edso localizado no sul-mato-grossense que encanta qualquer um.<\/p>\n<p>A pequena cidade do MS fica a 200 km da capital do estado. Um belo abrigo ecol\u00f3gico onde as a\u00e7\u00f5es do ser humano s\u00e3o quase nulas. Caso voc\u00ea seja um amante da natureza este destino merece sua visita.<\/p>\n<h3><strong>Op\u00e7\u00f5es de passeios em Bonito &#8211; MS<br \/>\n<\/strong><\/h3>\n<p>Bonito \u00e9 perfeito para renovas as energias do corpo e da alma. O contato com a natureza \u00e9 algo inexplic\u00e1vel.\u00a0 Aqui op\u00e7\u00f5es de passeio n\u00e3o v\u00e3o faltar:<\/p>\n<ul>\n<li>Mergulhar com peixes de diversas esp\u00e9cies,<\/li>\n<li>Fazer trilhas,<\/li>\n<li>Observar animais no <em>habitat <\/em>natural,<\/li>\n<li>Descer de rapel na gruta,<\/li>\n<li>Cavalgar,<\/li>\n<li>Tomar banho de cachoeira<\/li>\n<li>Admirar paisagens incr\u00edveis, etc.<\/li>\n<\/ul>\n<p>O fato de ser uma cidade pequena traz um charme incr\u00edvel, mas isso n\u00e3o interfere na \u00f3tima infraestrutura tur\u00edstica do destino. Muitos dizem que n\u00e3o deixa a desejar com a estrutura de grandes metr\u00f3poles.<\/p>\n<h3><strong>Aten\u00e7\u00e3o aos passeios em Bonito &#8211; MS<br \/>\n<\/strong><\/h3>\n<p>Seu dia aqui ser\u00e1 repleto de passeios. Estes devem ser pr\u00e9-agendados, e os pre\u00e7os s\u00e3o tabelados.<\/p>\n<p>Um passeio que \u00e9 indispens\u00e1vel voc\u00ea fazer \u00e9 mergulhar no Rio Sucuri (considerado uns dos mais transparentes do mundo) e tamb\u00e9m no Rio Prata.<\/p>\n<p>Aqui voc\u00ea tem op\u00e7\u00f5es de passeios mais radicais como descer o Abismo Anhumas ou mais tranquilos como visitar a Gruta do lago Azul.<\/p>\n<p>Bonito \u00e9 um verdadeiro aqu\u00e1rio natural, sendo um belo contive para realizar um mergulho inesquec\u00edvel.<\/p>\n<h3><strong>Bonito \u00e9 encantador at\u00e9 na gastronomia<\/strong><\/h3>\n<p>Alguma vez voc\u00ea j\u00e1 pensou em experimentar sashimi de piranha? Bonito n\u00e3o \u00e9 linda s\u00f3 por suas paisagens, sua gastronomia com requintes pantaneiros e do cerrado s\u00e3o incr\u00edveis. Principalmente a noite, os restaurantes ficam mais movimentados. \u00c9 nesta hora que \u00e9 o momento perfeito para voc\u00ea aproveitar, degustar de uma boa comida e ainda descansar dos passeios com algo mais light.<\/p>\n<p>Bonito pode ser uma caixa de surpresas e esta esperando ser aberta por voc\u00ea. Ideal para aventureiros e apaixonados pelo belo, que a natureza oferece.<\/p>\n<h3><strong>Arrumando as malas<\/strong><\/h3>\n<p>Itens indispens\u00e1veis na mala s\u00e3o um bom condicionador, como tamb\u00e9m um hidratante. Por conta da grande quantidade de magn\u00e9sio nos rios de Bonito, \u00e9 muito prov\u00e1vel que sua pele e cabelos fiquem ressecados.<\/p>\n<p>Outra coisa que recomendamos \u00e9 evitar ao m\u00e1ximo beber a agua destes rios, pois o magn\u00e9sio pode se tornar laxante em contato com seu organismo.<\/p>\n<p>Voc\u00ea pode levar protetor solar na mala, mas n\u00e3o poder\u00e1 utiliza-lo nos passeios em alguns rios para n\u00e3o degradar o meio ambiente. No entanto, tem alguns passeios que o uso \u00e9 indispens\u00e1vel, como, por exemplo, no Pantanal.<\/p>\n<h3><strong>Alta temporada em Bonito &#8211; MS <\/strong><\/h3>\n<p>Em per\u00edodos de alta temporada, busque se preparar com anteced\u00eancia, procurando uma ag\u00eancia de <a href=\"https:\/\/seuseguronoclick.com.br\/\">confian\u00e7a<\/a> para comprar os passeios.<\/p>\n<p>Recomendamos que antes at\u00e9 de chegar a Bonito &#8211; MS, procure alugar sua c\u00e2mara subaqu\u00e1tica, j\u00e1 que os pre\u00e7os podem ficar mais caros se deixar para depois.<\/p>\n<p>Este tipo de equipamento pode ser encontrado em algumas lojas no centro da cidade.<\/p>\n<h3><strong>Vida noturna<\/strong><\/h3>\n<p>Se voc\u00ea curtir os agitos da vida noturna, n\u00e3o alimente suas expectativas em rela\u00e7\u00e3o a Bonito &#8211; MS, pois este n\u00e3o \u00e9 foco da cidade.<\/p>\n<p>Durante a noite, os turistas querem jantar e depois descansar, j\u00e1 que os dias s\u00e3o bem intensos por conta dos passeios. Por vezes voc\u00ea pode at\u00e9 n\u00e3o perceber, mas todo o exerc\u00edcio que \u00e9 realizado junto com o calor, acabam dando aquela molezinha no corpo no fim dia.<\/p>\n<p>A op\u00e7\u00e3o ideal neste per\u00edodo \u00e9 caminhar pela rua principal, realizar algumas compras nas lojinhas e por fim escolher um restaurante para ter um bom jantar ou mesmo tomar alguns drinks.<\/p>\n<h2 class=\"cor_preta\" align=\"left\">Receba as not\u00edcias antes dos demais Assinantes!<\/h2>\n<p class=\"cor_preta\" align=\"left\">Clique para ativar as notifica\u00e7\u00f5es e receba antes de serem publicadas<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito &#8211; MS.<\/p>\n","protected":false},"author":1,"featured_media":8936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,6],"tags":[],"class_list":["post-8450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-america-do-sul","category-viagens-nacionais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.3 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bonito - MS &quot;o espet\u00e1culo da natureza&quot; - Blog Viagens<\/title>\n<meta name=\"description\" content=\"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonito - MS &quot;o espet\u00e1culo da natureza&quot; - Blog Viagens\" \/>\n<meta property=\"og:description\" content=\"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Viagens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/suaviagemnoclick\/?business_id=470313793386419\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-17T14:28:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-11T20:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"754\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"websitemix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitemix\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/\",\"url\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/\",\"name\":\"Bonito - MS \\\"o espet\u00e1culo da natureza\\\" - Blog Viagens\",\"isPartOf\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg\",\"datePublished\":\"2019-12-17T14:28:35+00:00\",\"dateModified\":\"2020-03-11T20:40:48+00:00\",\"author\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\"},\"description\":\"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.\",\"breadcrumb\":{\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage\",\"url\":\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg\",\"contentUrl\":\"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg\",\"width\":754,\"height\":268,\"caption\":\"bonito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/11ponto11servidor.com.br\/viagem\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonito &#8211; MS &#8220;o espet\u00e1culo da natureza&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/#website\",\"url\":\"https:\/\/11ponto11servidor.com.br\/viagem\/\",\"name\":\"Blog Viagens\",\"description\":\"SIAPE Servidor Federal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/11ponto11servidor.com.br\/viagem\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf\",\"name\":\"websitemix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83ea3ca973ba72c1d317f09d56ad47da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83ea3ca973ba72c1d317f09d56ad47da?s=96&d=mm&r=g\",\"caption\":\"websitemix\"},\"sameAs\":[\"https:\/\/11ponto11servidor.com.br\"],\"url\":\"https:\/\/11ponto11servidor.com.br\/viagem\/author\/websitemix\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bonito - MS \"o espet\u00e1culo da natureza\" - Blog Viagens","description":"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/","og_locale":"pt_BR","og_type":"article","og_title":"Bonito - MS \"o espet\u00e1culo da natureza\" - Blog Viagens","og_description":"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.","og_url":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/","og_site_name":"Blog Viagens","article_publisher":"https:\/\/business.facebook.com\/suaviagemnoclick\/?business_id=470313793386419","article_published_time":"2019-12-17T14:28:35+00:00","article_modified_time":"2020-03-11T20:40:48+00:00","og_image":[{"width":754,"height":268,"url":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg","type":"image\/jpeg"}],"author":"websitemix","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitemix","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/","url":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/","name":"Bonito - MS \"o espet\u00e1culo da natureza\" - Blog Viagens","isPartOf":{"@id":"https:\/\/11ponto11servidor.com.br\/viagem\/#website"},"primaryImageOfPage":{"@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage"},"image":{"@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage"},"thumbnailUrl":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg","datePublished":"2019-12-17T14:28:35+00:00","dateModified":"2020-03-11T20:40:48+00:00","author":{"@id":"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf"},"description":"Um destino espetacular onde o contato com a natureza \u00e9 constante. De rios de \u00e1guas l\u00edmpidas e transparente, a grutas lind\u00edssimas. Est\u00e1 Bonito - MS.","breadcrumb":{"@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#primaryimage","url":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg","contentUrl":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-content\/uploads\/sites\/5\/2019\/12\/destaque-bonito-1.jpg","width":754,"height":268,"caption":"bonito"},{"@type":"BreadcrumbList","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/viagens-nacionais\/bonito-ms-o-espetaculo-da-natureza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/11ponto11servidor.com.br\/viagem\/"},{"@type":"ListItem","position":2,"name":"Bonito &#8211; MS &#8220;o espet\u00e1culo da natureza&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/#website","url":"https:\/\/11ponto11servidor.com.br\/viagem\/","name":"Blog Viagens","description":"SIAPE Servidor Federal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/11ponto11servidor.com.br\/viagem\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/641e1af8b22c69725a1d604fb8959bcf","name":"websitemix","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/11ponto11servidor.com.br\/viagem\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83ea3ca973ba72c1d317f09d56ad47da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ea3ca973ba72c1d317f09d56ad47da?s=96&d=mm&r=g","caption":"websitemix"},"sameAs":["https:\/\/11ponto11servidor.com.br"],"url":"https:\/\/11ponto11servidor.com.br\/viagem\/author\/websitemix\/"}]}},"_links":{"self":[{"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/posts\/8450"}],"collection":[{"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/comments?post=8450"}],"version-history":[{"count":0,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/posts\/8450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/media\/8936"}],"wp:attachment":[{"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/media?parent=8450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/categories?post=8450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/11ponto11servidor.com.br\/viagem\/wp-json\/wp\/v2\/tags?post=8450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}